{"id":9560,"date":"2026-07-13T21:57:58","date_gmt":"2026-07-14T00:57:58","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9560"},"modified":"2026-07-13T21:57:58","modified_gmt":"2026-07-14T00:57:58","slug":"loteria-correntina-prepara-una-denuncia-contra-200-sitios-de-apuestas-ilegales","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/13\/loteria-correntina-prepara-una-denuncia-contra-200-sitios-de-apuestas-ilegales\/","title":{"rendered":"Loter\u00eda Correntina prepara una denuncia contra 200 sitios de apuestas ilegales"},"content":{"rendered":"<p>El presidente de Loter\u00eda Correntina, Javier Bee Sellar\u00e9s, advirti\u00f3 a Radio Sudamericana que entre el 70% y el 80% del dinero que se apuesta online en Argentina se realiza en plataformas clandestinas. Tambi\u00e9n anunci\u00f3 el lanzamiento de una quiniela poceada extraordinaria para Navidad.<\/p>\n<p>El presidente de Loter\u00eda Correntina, Javier Bee Sellar\u00e9s, confirm\u00f3 a Radio Sudamericana que el organismo presentar\u00e1 una nueva denuncia contra alrededor de 200 sitios de apuestas online ilegales que operan en la provincia. El funcionario explic\u00f3 que la medida forma parte de una estrategia para combatir el juego clandestino y proteger, especialmente, a los menores de edad.<\/p>\n<p>Bee Sellar\u00e9s se\u00f1al\u00f3 que una de las principales preocupaciones es el acceso de adolescentes a las plataformas ilegales de apuestas. En ese sentido, remarc\u00f3 que los sitios habilitados cuentan con sistemas de verificaci\u00f3n biom\u00e9trica para corroborar la edad de los usuarios. &#8220;Hay que masificar el mensaje de que las apuestas online se tienen que hacer a trav\u00e9s de los canales legales. Much\u00edsimos menores empiezan jugando creyendo que es un juego y terminan en situaciones muy delicadas&#8221;, expres\u00f3.<\/p>\n<p>El titular de Loter\u00eda Correntina precis\u00f3 que la denuncia en preparaci\u00f3n incluir\u00e1 pruebas para acreditar que esas plataformas captan apuestas de manera clandestina en la provincia. Adem\u00e1s, record\u00f3 que durante el a\u00f1o pasado el organismo present\u00f3 dos denuncias que involucraron a 600 sitios ilegales, en un trabajo conjunto con Loter\u00eda del Chaco.<\/p>\n<p>Bee Sellar\u00e9s sostuvo que &#8220;de cada 100 pesos que se juegan en el online, entre 70 y 80 pesos son ilegales&#8221;. Tambi\u00e9n consider\u00f3 que el juego clandestino tradicional, como la quiniela ilegal, disminuy\u00f3 considerablemente debido a la amplia oferta de sorteos oficiales disponibles.<\/p>\n<p><b>Gordo de Navidad<br \/>\n<\/b><br \/>\nPor otra parte, el funcionario adelant\u00f3 que Loter\u00eda Correntina trabaja en el lanzamiento de una quiniela poceada extraordinaria de Navidad, que buscar\u00e1 recuperar el esp\u00edritu del tradicional Gordo de Navidad.<\/p>\n<p>Seg\u00fan explic\u00f3, el nuevo juego contar\u00e1 con un premio importante que ser\u00e1 anunciado en los pr\u00f3ximos d\u00edas y estar\u00e1 disponible inicialmente a trav\u00e9s de la plataforma Correntina Online, para luego comercializarse tambi\u00e9n en las agencias oficiales durante los 60 d\u00edas previos al sorteo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Loter\u00eda Correntina, Javier Bee Sellar\u00e9s, advirti\u00f3 a Radio Sudamericana que entre el 70% y el 80% del dinero que se apuesta online en Argentina se realiza en plataformas clandestinas. Tambi\u00e9n anunci\u00f3 el lanzamiento de una quiniela poceada extraordinaria para Navidad. El presidente de Loter\u00eda Correntina, Javier Bee Sellar\u00e9s, confirm\u00f3 a Radio Sudamericana [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-9560","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provincia"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9560"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9560\/revisions"}],"predecessor-version":[{"id":9562,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9560\/revisions\/9562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9561"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}