{"id":9452,"date":"2026-07-11T23:17:27","date_gmt":"2026-07-12T02:17:27","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9452"},"modified":"2026-07-11T23:17:27","modified_gmt":"2026-07-12T02:17:27","slug":"a-casi-once-meses-regatas-analiza-propuestas-para-los-trabajos-de-reconstruccion-de-su-estadio","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/11\/a-casi-once-meses-regatas-analiza-propuestas-para-los-trabajos-de-reconstruccion-de-su-estadio\/","title":{"rendered":"A CASI ONCE MESES: Regatas analiza propuestas para los trabajos de reconstrucci\u00f3n de su estadio"},"content":{"rendered":"<p>La instituci\u00f3n del Parque Mitre pretende que las nuevas obras eleven la capacidad del Jos\u00e9 Jorge Contte a 7.000 personas.<\/p>\n<p>LA IDEA ES ANALIZAR PROPUESTAS EMPRESARIALES PARA EL NUEVO ESTADIO DE LOS SUE\u00d1OS.<\/p>\n<p>El 13 de agosto de 2025 en horas de la siesta fue una fecha tr\u00e1gica para la gente de Regatas, ya que ese d\u00eda se desplom\u00f3 el techo del Estadio de los Sue\u00f1os. A casi once meses del derrumbe en el estadio Jos\u00e9 Jorge Contte del Club de Regatas Corrientes, las obras de reconstrucci\u00f3n todav\u00eda no han iniciado, por lo que la dirigencia de la instituci\u00f3n del Parque Mitre comenz\u00f3 a analizar propuestas empresariales para conseguir los fondos necesarios para activar los trabajos.<\/p>\n<p>La intenci\u00f3n de este grupo empresarial es aportar los fondos necesarios para la reconstrucci\u00f3n total del Estadio de los Sue\u00f1os, adem\u00e1s de elevar la capacidad a alrededor de 7.000 personas con el fin de que tambi\u00e9n pueda ser el escenario para recitales y otros eventos art\u00edsticos.<\/p>\n<p>Vale recordar que el club del Parque Mitre ya cuenta con el decreto firmado por el exgobernador Gustavo Vald\u00e9s bajo la figura de cooperaci\u00f3n entre el Gobierno provincial y la entidad deportiva para llevar adelante la reconstrucci\u00f3n del estadio, pero hasta el momento ese decreto no se hizo efectivo, aunque se descuenta que as\u00ed ser\u00e1.<\/p>\n<p>El presidente del club, Eduardo Tassano, hab\u00eda afirmado hace no mucho que &#8220;lo m\u00e1s importante este a\u00f1o va a ser el estadio, vamos a trabajar fuertemente en eso&#8221;.<\/p>\n<p>San Mart\u00edn ya arranc\u00f3 con los trabajos en su piso<\/p>\n<p>El Club San Mart\u00edn de Corrientes puso en marcha una importante obra de infraestructura con la renovaci\u00f3n integral del parquet de la cancha principal, dando inicio a la primera etapa de un plan de mejoras que alcanzar\u00e1 distintos espacios de la instituci\u00f3n.<\/p>\n<p>La obra consiste en el levantamiento completo del piso actual y la construcci\u00f3n de un nuevo piso deportivo. Los trabajos ya comenzaron y tendr\u00e1n una duraci\u00f3n aproximada de un mes, forman parte de un proyecto integral de infraestructura impulsado por la instituci\u00f3n cuyo objetivo es seguir mejorando las instalaciones para ofrecer espacios m\u00e1s c\u00f3modos y funcionales a su comunidad.<\/p>\n<p>La ejecuci\u00f3n de los trabajos coincidir\u00e1 en gran parte con el receso escolar de invierno, permitiendo optimizar los tiempos de obra y minimizar el impacto sobre las actividades deportivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La instituci\u00f3n del Parque Mitre pretende que las nuevas obras eleven la capacidad del Jos\u00e9 Jorge Contte a 7.000 personas. LA IDEA ES ANALIZAR PROPUESTAS EMPRESARIALES PARA EL NUEVO ESTADIO DE LOS SUE\u00d1OS. El 13 de agosto de 2025 en horas de la siesta fue una fecha tr\u00e1gica para la gente de Regatas, ya que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-9452","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9452"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9452\/revisions"}],"predecessor-version":[{"id":9454,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9452\/revisions\/9454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9453"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}