{"id":9433,"date":"2026-07-11T12:58:22","date_gmt":"2026-07-11T15:58:22","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9433"},"modified":"2026-07-11T12:58:22","modified_gmt":"2026-07-11T15:58:22","slug":"en-curuzu-cuatia-valdes-inauguro-la-fiesta-provincial-del-locro-y-ratifico-su-apoyo-para-proyectarla-a-nivel-nacional","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/11\/en-curuzu-cuatia-valdes-inauguro-la-fiesta-provincial-del-locro-y-ratifico-su-apoyo-para-proyectarla-a-nivel-nacional\/","title":{"rendered":"EN CURUZ\u00da CUATI\u00c1 Vald\u00e9s inaugur\u00f3 la Fiesta Provincial del Locro y ratific\u00f3 su apoyo para proyectarla a nivel nacional"},"content":{"rendered":"<p>El gobernador Juan Pablo Vald\u00e9s inaugur\u00f3 este viernes una nueva edici\u00f3n de la Fiesta Provincial del Locro en Curuz\u00fa Cuati\u00e1. La destac\u00f3 por su importancia a nivel cultural pero tambi\u00e9n como generadora de turismo y oportunidades para emprendedores.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.powernoticias.com\/images\/202607111550336331\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.powernoticias.com\/images\/202607111550254531\" \/><\/p>\n<p>El cors\u00f3dromo \u00abLa Sucursal del Cielo\u00bb es el escenario de la 5\u00b0 Fiesta Provincial del Locro, un evento de tres jornadas que re\u00fane a cocineros, artesanos y miles de visitantes. El acto de apertura cont\u00f3 con una fuerte presencia institucional encabezada por el gobernador Juan Pablo Vald\u00e9s, quien dej\u00f3 en claro el potencial tur\u00edstico y econ\u00f3mico de la tradicional celebraci\u00f3n.<\/p>\n<p>Al inaugurar el evento, el gobernador Juan Pablo Vald\u00e9s expres\u00f3 su satisfacci\u00f3n por el crecimiento de la celebraci\u00f3n y destac\u00f3 la infraestructura del predio. Adem\u00e1s, ratific\u00f3 el acompa\u00f1amiento de la Provincia para que el evento obtenga el rango m\u00e1ximo: &#8220;Todos juntos vamos a trabajar para que esto sea posible porque realmente vienen haciendo un trabajo enorme&#8221;, afirm\u00f3 respecto a la postulaci\u00f3n como Fiesta Nacional.<\/p>\n<p>El mandatario analiz\u00f3 el impacto socioecon\u00f3mico de la propuesta y se\u00f1al\u00f3 que &#8220;m\u00e1s all\u00e1 de verlo como una fiesta, creo que es una oportunidad para muchos\u201d, dijo en referencia a emprendedores, artistas y a trabajadores de distintos oficios.<\/p>\n<p>Finalmente, Vald\u00e9s traz\u00f3 un paralelismo entre la receta tradicional y la construcci\u00f3n social: &#8220;As\u00ed como el locro lleva todos los ingredientes para generar esa comida t\u00edpica tan rica, yo quiero decirles que para ser una gran provincia necesitamos de cada uno de ustedes y que cada uno trabaje, que empuje desde el lugar que toque&#8221;, invit\u00f3.<\/p>\n<p>A la comitiva oficial, se sumaron tambi\u00e9n a la celebraci\u00f3n el Ministro Secretario General, Juan Pablo Fornaroli, el titular de la cartera tur\u00edstica provincial, Juan Enrique Braillard Poccard, el Ministro de Seguridad Ad\u00e1n Gaya y el de Desarrollo Social, el curuzucuate\u00f1o Jos\u00e9 Irigoyen.<\/p>\n<p>La identidad de la comunidad<\/p>\n<p>A su turno, la intendente de Curuz\u00fa Cuati\u00e1, Ver\u00f3nica Esp\u00edndola, dio la bienvenida a las familias y autoridades presentes, rescatando el valor hist\u00f3rico de la localidad como el primer pueblo patrio fundado por Manuel Belgrano. &#8220;Esta fiesta es el reflejo exacto de esa hermandad. Es la familia unida alrededor del fuego, el abuelo que le ense\u00f1a al nieto los secretos gastron\u00f3micos de la le\u00f1a y de la espera&#8221;, enfatiz\u00f3.<\/p>\n<p>Esp\u00edndola repas\u00f3 los 19 a\u00f1os de historia del encuentro gastron\u00f3mico local y valor\u00f3 el salto hacia la \u00f3rbita provincial: &#8220;Vemos que esa semilla se convirti\u00f3 en un pilar cultural indiscutible de toda la provincia de Corrientes. El desaf\u00edo que compartimos ahora con toda la comunidad es enorme. Consolidar este crecimiento, potenciarlo y lograr que Curuz\u00fa Cuati\u00e1 sea un faro tur\u00edstico definitivo en el mapa nacional&#8221;, sostuvo.<\/p>\n<p>La jefa comunal cerr\u00f3 su discurso agradeciendo el apoyo del sector privado, los trabajadores municipales y los cocineros, reforzando la impronta de su gesti\u00f3n: &#8220;Nuestro lema, Con Voz, no es una frase, es una convicci\u00f3n. Significa escuchar, trabajar en equipo, generar oportunidades y apostar al crecimiento&#8221;, destac\u00f3 al final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Juan Pablo Vald\u00e9s inaugur\u00f3 este viernes una nueva edici\u00f3n de la Fiesta Provincial del Locro en Curuz\u00fa Cuati\u00e1. La destac\u00f3 por su importancia a nivel cultural pero tambi\u00e9n como generadora de turismo y oportunidades para emprendedores. El cors\u00f3dromo \u00abLa Sucursal del Cielo\u00bb es el escenario de la 5\u00b0 Fiesta Provincial del Locro, un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-9433","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provincia"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9433"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9433\/revisions"}],"predecessor-version":[{"id":9435,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9433\/revisions\/9435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9434"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}