{"id":9429,"date":"2026-07-11T12:55:49","date_gmt":"2026-07-11T15:55:49","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9429"},"modified":"2026-07-11T12:55:49","modified_gmt":"2026-07-11T15:55:49","slug":"proyeccion-del-indec-corrientes-alcanzo-los-1-208-334-habitantes-cuales-son-los-departamentos-mas-poblados","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/11\/proyeccion-del-indec-corrientes-alcanzo-los-1-208-334-habitantes-cuales-son-los-departamentos-mas-poblados\/","title":{"rendered":"Proyecci\u00f3n del Indec Corrientes alcanz\u00f3 los 1.208.334 habitantes: cu\u00e1les son los departamentos m\u00e1s poblados"},"content":{"rendered":"<p>El informe detalla cu\u00e1ntas personas viven en cada sector de la provincia y c\u00f3mo se posiciona el territorio correntino dentro del NEA. Con 105.482 habitantes, Goya es el departamento del interior m\u00e1s poblado, despu\u00e9s de capital donde la cantidad de habitantes est\u00e1 estimada en 437.771 personas.<\/p>\n<p>Corrientes ya supera los 1,2 millones de habitantes, de acuerdo con la \u00faltima actualizaci\u00f3n de las proyecciones de poblaci\u00f3n difundida por el Instituto Nacional de Estad\u00edstica y Censos (Indec). El informe, elaborado con datos al 1 de julio de 2026, estima que en la provincia viven 1.208.334 personas, consolid\u00e1ndola como una de las jurisdicciones m\u00e1s pobladas del Nordeste argentino.<\/p>\n<p>Seg\u00fan las estimaciones oficiales, del total de habitantes 600.001 son varones y 608.333 mujeres. A nivel nacional, el Indec proyecta una poblaci\u00f3n de 46.466.688 personas, de las cuales 22.855.676 son varones y 23.611.012 mujeres.<\/p>\n<p>El relevamiento tambi\u00e9n muestra c\u00f3mo se distribuye la poblaci\u00f3n dentro de la provincia. Capital contin\u00faa siendo el departamento con mayor cantidad de habitantes, con una poblaci\u00f3n estimada de 437.771 personas, lo que representa m\u00e1s de un tercio del total provincial. Le siguen Goya, con 105.482 habitantes; Santo Tom\u00e9, con 71.320; Paso de los Libres, con 56.448; y Curuz\u00fa Cuati\u00e1, con 50.990.<\/p>\n<p>M\u00e1s atr\u00e1s aparecen Mercedes, con 49.371 habitantes; Monte Caseros, con 45.697; y Bella Vista, con 44.121. En el otro extremo del ranking, los departamentos con menor poblaci\u00f3n estimada son Ber\u00f3n de Astrada, con 2.795 habitantes, y General Alvear, con 9.045.<\/p>\n<p>En el contexto regional, el Nordeste argentino (NEA) re\u00fane una poblaci\u00f3n estimada de 4.433.519 personas. Dentro de ese total, Misiones es la provincia m\u00e1s poblada, con 1.355.029 habitantes, seguida por Chaco, con 1.241.280; Corrientes, con 1.208.334; y Formosa, con 628.876, seg\u00fan las proyecciones oficiales del Indec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El informe detalla cu\u00e1ntas personas viven en cada sector de la provincia y c\u00f3mo se posiciona el territorio correntino dentro del NEA. Con 105.482 habitantes, Goya es el departamento del interior m\u00e1s poblado, despu\u00e9s de capital donde la cantidad de habitantes est\u00e1 estimada en 437.771 personas. Corrientes ya supera los 1,2 millones de habitantes, de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-9429","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provincia"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9429"}],"version-history":[{"count":2,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9429\/revisions"}],"predecessor-version":[{"id":9432,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9429\/revisions\/9432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9430"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}