{"id":9344,"date":"2026-07-10T13:39:43","date_gmt":"2026-07-10T16:39:43","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9344"},"modified":"2026-07-10T13:39:43","modified_gmt":"2026-07-10T16:39:43","slug":"la-afa-sufrio-un-hackeo-y-divulgo-mails-denunciando-al-arbitraje-ante-egipto","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/10\/la-afa-sufrio-un-hackeo-y-divulgo-mails-denunciando-al-arbitraje-ante-egipto\/","title":{"rendered":"La AFA sufri\u00f3 un hackeo y divulg\u00f3 mails denunciando al arbitraje ante Egipto"},"content":{"rendered":"<p>El hecho se produjo luego del triunfo de Argentina sobre el combinado egipcio en el Mundial 2026.<\/p>\n<p>La Asociaci\u00f3n del F\u00fatbol Argentino (AFA) reconoci\u00f3 ayer un ciberataque tras la difusi\u00f3n de correos que cuestionaban el arbitraje del franc\u00e9s Fran\u00e7ois Letexier en el partido de octavos de final del Mundial 2026 en el que Argentina elimin\u00f3 a Egipto.<\/p>\n<p>Seg\u00fan se inform\u00f3, el comunicado \u2014enviado desde una cuenta vinculada a AFA Medios a un grupo de periodistas\u2014 inclu\u00eda la frase: \u201cArgentina no gan\u00f3. La victoria fue arrebatada por decisiones arbitrales corruptas\u201d.<\/p>\n<p>El episodio se produjo luego de que, desde la delegaci\u00f3n egipcia, continuaran los reclamos por la actuaci\u00f3n del \u00e1rbitro, pese a que las repeticiones de las jugadas clave no muestran una direcci\u00f3n tendenciosa. Fuentes de la AFA dijeron que el mail fue producto de un hackeo y que la informaci\u00f3n de su base de datos hab\u00eda sido ofrecida en foros por un grupo hacker egipcio, que habr\u00eda accedido a direcciones de correo electr\u00f3nico, contrase\u00f1as y direcciones IP.<\/p>\n<p>Varios periodistas acreditados aseguraron haber recibido el mensaje en el que tambi\u00e9n se alababa a la selecci\u00f3n africana por \u201cabsoluto honor, pasi\u00f3n y dominio t\u00e1ctico\u201d y se advert\u00eda: \u201csi no hay justicia en la cancha, no esperen paz en sus redes\u201d. El texto acusaba adem\u00e1s a Egipto de haber sufrido un arbitraje perjudicial \u201cpor apoyar a Palestina\u201d y cerraba con la consigna: \u201cLos faraones siempre se alzan. No olvidamos. No perdonamos\u201d.<\/p>\n<p>Las frases del mail coinciden con declaraciones p\u00fablicas del entrenador egipcio Hossam Hassan y del jugador Mostafa Ziko, que tras el partido cuestionaron al arbitraje. No obstante, desde la AFA aclararon que el correo no fue \u201cgenerado ni autorizado\u201d por su equipo de comunicaci\u00f3n y pidieron a los destinatarios desestimar el contenido.<\/p>\n<p>La entidad inform\u00f3 que detect\u00f3 el \u201cposible env\u00edo\u201d desde una cuenta institucional, que est\u00e1 analizando el alcance del acceso no autorizado y que trabaja \u201cpara esclarecer lo ocurrido y adoptar las medidas de seguridad necesarias\u201d. En paralelo, las autoridades del seleccionado argentino enfocan la atenci\u00f3n en el pr\u00f3ximo rival: Suiza, en los cuartos de final, con la mira en alcanzar una segunda semifinal consecutiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hecho se produjo luego del triunfo de Argentina sobre el combinado egipcio en el Mundial 2026. La Asociaci\u00f3n del F\u00fatbol Argentino (AFA) reconoci\u00f3 ayer un ciberataque tras la difusi\u00f3n de correos que cuestionaban el arbitraje del franc\u00e9s Fran\u00e7ois Letexier en el partido de octavos de final del Mundial 2026 en el que Argentina elimin\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-9344","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9344"}],"version-history":[{"count":2,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9344\/revisions"}],"predecessor-version":[{"id":9347,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9344\/revisions\/9347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9345"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}