{"id":9325,"date":"2026-07-09T20:46:30","date_gmt":"2026-07-09T23:46:30","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9325"},"modified":"2026-07-09T20:46:30","modified_gmt":"2026-07-09T23:46:30","slug":"francia-vencio-a-marruecos-y-es-semifinalista-del-mundial-2026","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/09\/francia-vencio-a-marruecos-y-es-semifinalista-del-mundial-2026\/","title":{"rendered":"Francia venci\u00f3 a Marruecos y es semifinalista del Mundial 2026"},"content":{"rendered":"<p>Kylian Mbapp\u00e9 y Ousmane Demb\u00e9l\u00e9 convirtieron los goles y esperan a Espa\u00f1a o B\u00e9lgica como pr\u00f3ximo rival<\/p>\n<p>Francia le gan\u00f3 con autoridad a Marruecos por 2 a 0 en el Boston Stadium y es el primer semifinalista del Mundial 2026.<\/p>\n<p>Con los goles de Kylian Mbapp\u00e9 a los 15 minutos del segundo tiempo y Ousmane Demb\u00e9l\u00e9 a los 21, Francia no pas\u00f3 sobresaltos ante el equipo africano y jugar\u00e1 una de las semifinales ante Espa\u00f1a o B\u00e9lgica.<\/p>\n<p>El desarrollo del partido mostr\u00f3 a un conjunto marroqu\u00ed completamente replegado, con la intenci\u00f3n de cerrar espacios y resistir los avances franceses.<\/p>\n<p>La estrategia de los dirigidos por Mohamed Ouahbi dio resultados durante gran parte de la primera mitad, en buena medida gracias a la actuaci\u00f3n de Bounou, que respondi\u00f3 con dos intervenciones decisivas en los primeros cuatro minutos ante Kylian Mbapp\u00e9 y D\u00e9sir\u00e9 Dou\u00e9.<\/p>\n<p>Antes de la pausa de hidrataci\u00f3n, Francia tuvo una oportunidad inmejorable para abrir el marcador, cuando Noussair Mazraoui cometi\u00f3 una infracci\u00f3n sobre Mbapp\u00e9 dentro del \u00e1rea y el \u00e1rbitro argentino Facundo Tello sancion\u00f3 penal.<\/p>\n<p>El propio delantero del Real Madrid ejecut\u00f3 desde los doce pasos, pero Bounou volvi\u00f3 a imponerse y mantuvo el empate tras una muy mala ejecuci\u00f3n del goleador.<\/p>\n<p>Francia sigui\u00f3 dominando el juego, aunque sin eficacia: Ousmane Demb\u00e9l\u00e9 estuvo cerca con un remate colocado que pas\u00f3 junto al palo derecho, mientras que Lucas Digne prob\u00f3 desde media distancia y estrell\u00f3 su disparo en el travesa\u00f1o antes del descanso.<\/p>\n<p>La diferencia lleg\u00f3 en el complemento cuando a los 60 minutos, Mbapp\u00e9 recibi\u00f3 un pase de Dou\u00e9 y defini\u00f3 con un remate con efecto al palo m\u00e1s alejado para marcar el 1 a 0.<\/p>\n<p>Apenas seis minutos despu\u00e9s, el delantero particip\u00f3 en otra acci\u00f3n ofensiva al asistir a Demb\u00e9l\u00e9, quien avanz\u00f3 desde la medialuna y defini\u00f3 junto al palo izquierdo para establecer el 2 a 0 definitivo.<\/p>\n<p>Marruecos busc\u00f3 descontar con un remate de Azzedine Ounahi que control\u00f3 Mike Maignan y un cabezazo de Neil El Aynaoui que sali\u00f3 apenas desviado, pero no logr\u00f3 modificar el resultado.<\/p>\n<p>Francia cerr\u00f3 la victoria y avanz\u00f3 a las semifinales del Mundial, en donde tendr\u00e1 el duro trabajo de medirse ante Espa\u00f1a de Lamine Yamal o B\u00e9lgica de Thibaut Courtois.<\/p>\n<p>S\u00edntesis del partido:<br \/>\nMundial 2026.<br \/>\nCuartos de final.<br \/>\nFrancia 2-0 Marruecos.<br \/>\nEstadio: Boston Stadium.<br \/>\n\u00c1rbitro: Facundo Tello (Argentina).<br \/>\nVAR: Hern\u00e1n Mastrangelo (Argentina).<br \/>\nFrancia: Mike Maignan; Jules Kound\u00e9, Dayot Upamecano, William Saliba, Lucas Digne; Manu Kon\u00e9, Adrien Rabiot; Ousmane Demb\u00e9l\u00e9, Michael Olise, D\u00e9sir\u00e9 Dou\u00e9; Kylian Mbapp\u00e9. DT: Didier Deschamps.<\/p>\n<p>Marruecos: Yassine Bounou; Achfraf Hakimi, Issa Diop, Noussair Mazraoui, Anass Salah-Eddine; Ayyoub Bouaddi, Neil Al Aynaoui; Brahim D\u00edaz, Azzedine Ounahi, Chemsdine Talbi; Bilal El Khanouss. DT: Mohamed Ouahbi.<\/p>\n<p>Goles en el segundo tiempo: 15m Kylian Mbapp\u00e9 (F); 21m Ousmane Demb\u00e9l\u00e9 (F).<\/p>\n<p>Incidencias en el primer tiempo: 28m Yassine Bounou (M), le ataj\u00f3 un penal a Kylian Mbapp\u00e9 (F).<\/p>\n<p>Cambios en el segundo tiempo: 17m Sofyan Amrabat por Bouaddi (M); Soufiane Rahimi por El Khanouss (M); 25m Warren Za\u00efre-Emery por Kon\u00e9 (F); 29m Gessime Yassine por Diaz (M); Zakaria El Ouahdi por Salah-Eddine (M); 32m Jean-Philippe Mateta por Mbapp\u00e9 (F); Bradley Barcola por Dou\u00e9 (F); 40m Amine Sbai por Talbi (M); 42m Malo Gusto por Kound\u00e9 (F).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kylian Mbapp\u00e9 y Ousmane Demb\u00e9l\u00e9 convirtieron los goles y esperan a Espa\u00f1a o B\u00e9lgica como pr\u00f3ximo rival Francia le gan\u00f3 con autoridad a Marruecos por 2 a 0 en el Boston Stadium y es el primer semifinalista del Mundial 2026. Con los goles de Kylian Mbapp\u00e9 a los 15 minutos del segundo tiempo y Ousmane [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-9325","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9325"}],"version-history":[{"count":2,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9325\/revisions"}],"predecessor-version":[{"id":9328,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9325\/revisions\/9328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9326"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}