{"id":9203,"date":"2026-07-08T15:08:46","date_gmt":"2026-07-08T18:08:46","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9203"},"modified":"2026-07-08T15:08:46","modified_gmt":"2026-07-08T18:08:46","slug":"goya-condenan-a-la-pena-maxima-a-un-hombre-por-desobedecer-una-orden-judicial-en-un-caso-de-violencia-familiar-y-de-genero","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/08\/goya-condenan-a-la-pena-maxima-a-un-hombre-por-desobedecer-una-orden-judicial-en-un-caso-de-violencia-familiar-y-de-genero\/","title":{"rendered":"GOYA: Condenan a la pena m\u00e1xima a un hombre por desobedecer una orden judicial en un caso de violencia familiar y de g\u00e9nero"},"content":{"rendered":"<p>El Juez de Juicio Unipersonal dict\u00f3 la pena de un a\u00f1o de prisi\u00f3n de cumplimiento efectivo para Maximiliano M. M. Marsilli. Adem\u00e1s, se le revoc\u00f3 la condicionalidad de una condena previa, se orden\u00f3 su unificaci\u00f3n y se dispuso su inmediata detenci\u00f3n bajo prisi\u00f3n preventiva por riesgo procesal. El fallo se fundament\u00f3 rigurosamente bajo las perspectivas de ni\u00f1ez y de g\u00e9nero.<\/p>\n<p>El Juez de Juicio Unipersonal de la Segunda Circunscripci\u00f3n Judicial de la ciudad de Goya, Dr. Ricardo Diego Carbajal, conden\u00f3 a Maximiliano M. M. Marsilli a la pena de un a\u00f1o de prisi\u00f3n de cumplimiento efectivo, la sanci\u00f3n m\u00e1xima prevista para el delito de desobediencia a una orden judicial.<\/p>\n<p>El imputado, quien lleg\u00f3 al debate en libertad, estaba acusado de haber quebrantado una restricci\u00f3n emanada originalmente por el Juzgado de Familia N\u00b0 1 de Goya, a cargo de la Dra. Silvina Racigh, dictada con el fin de proteger a su ex pareja y a sus tres hijas menores de edad.<\/p>\n<p>La resoluci\u00f3n del magistrado hizo lugar a las peticiones efectuadas por la Fiscal, Dra. Mar\u00eda Eugenia Ballar\u00e1, y por el querellante, Dr. Conrado Rudy P\u00e9rez. Asimismo, el Dr. Carbajal dict\u00f3 la revocaci\u00f3n de la condicionalidad y dispuso la futura unificaci\u00f3n de penas (en virtud de los art\u00edculos 26 y 27 del C\u00f3digo Penal Argentino) respecto de otra condena anterior de un a\u00f1o de prisi\u00f3n que el imputado manten\u00eda en suspenso desde el a\u00f1o 2022.<\/p>\n<p><b>Prisi\u00f3n preventiva inmediata y perspectiva de derechos<br \/>\n<\/b><br \/>\nConsiderando la existencia de riesgo procesal, en la misma audiencia de juicio se decret\u00f3 la inmediata detenci\u00f3n y la prisi\u00f3n preventiva del ahora condenado. Al momento de fundar la sentencia, el juez destac\u00f3 de manera central la aplicaci\u00f3n de las perspectivas de ni\u00f1ez y de g\u00e9nero, considerando la vulnerabilidad de las v\u00edctimas directas afectadas por el incumplimiento del agresor.<\/p>\n<p>El debate se desarroll\u00f3 a lo largo de dos audiencias consecutivas que iniciaron el pasado 6 de julio y culminaron el d\u00eda de ayer, 7 de julio. Durante el proceso comparecieron un total de 8 testigos, mientras que la defensa t\u00e9cnica del imputado estuvo a cargo del Dr. Juan Manuel Balestra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Juez de Juicio Unipersonal dict\u00f3 la pena de un a\u00f1o de prisi\u00f3n de cumplimiento efectivo para Maximiliano M. M. Marsilli. Adem\u00e1s, se le revoc\u00f3 la condicionalidad de una condena previa, se orden\u00f3 su unificaci\u00f3n y se dispuso su inmediata detenci\u00f3n bajo prisi\u00f3n preventiva por riesgo procesal. El fallo se fundament\u00f3 rigurosamente bajo las perspectivas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-9203","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9203"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9203\/revisions"}],"predecessor-version":[{"id":9205,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9203\/revisions\/9205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9204"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}