{"id":9030,"date":"2026-07-06T23:06:56","date_gmt":"2026-07-07T02:06:56","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=9030"},"modified":"2026-07-07T00:22:07","modified_gmt":"2026-07-07T03:22:07","slug":"el-presupuesto-educativo-a-nivel-nacional-se-redujo-casi-50-en-los-ultimos-dos-anos","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/06\/el-presupuesto-educativo-a-nivel-nacional-se-redujo-casi-50-en-los-ultimos-dos-anos\/","title":{"rendered":"El presupuesto educativo a nivel nacional se redujo casi 50% en los \u00faltimos dos a\u00f1os"},"content":{"rendered":"<p>La educaci\u00f3n fue uno de los sectores que m\u00e1s sufri\u00f3 la motosierra desde el inicio de la actual gesti\u00f3n. El debate por los modelos de financiamiento<\/p>\n<p>Mientras que las universidades siguen a la espera del cumplimiento de la ley de financiamiento aprobada en el Congreso y ratificada por la Corte Suprema, un estudio de la UBA calcul\u00f3 que el presupuesto educativo cay\u00f3 47,7% en el bienio 2024-2025.<\/p>\n<p>As\u00ed surge de un informe del Instituto Interdisciplinario de Econom\u00eda Pol\u00edtica (IIEP) de la Facultad de Ciencias Econ\u00f3micas, que destac\u00f3 que en 2024 la funci\u00f3n Educaci\u00f3n y Cultura present\u00f3 una contracci\u00f3n real de 43,2% respecto del a\u00f1o anterior y redujo su participaci\u00f3n en el PBI en aproximadamente 0,6 puntos porcentuales.<\/p>\n<p>Si bien esto ocurre en el marco de un proceso m\u00e1s amplio de ajuste del gasto p\u00fablico nacional, la &#8220;motosierra&#8221; fue relativamente m\u00e1s profunda en esta \u00e1rea.<\/p>\n<p>Por su magnitud y composici\u00f3n, esta ca\u00edda se explica en gran medida por la discontinuaci\u00f3n del Fondo Nacional de Incentivo Docente (FONID), que complementaba los salarios docentes en las provincias.<\/p>\n<p>Como consecuencia, las jurisdicciones debieron asumir una mayor responsabilidad financiera, lo que reforz\u00f3 el car\u00e1cter descentralizado del sistema educativo argentino.<\/p>\n<p>En 2025 se consolid\u00f3 la trayectoria iniciada en 2024, con un retroceso de 7,9% en t\u00e9rminos reales. &#8220;El ajuste volvi\u00f3 a concentrarse en algunos de los principales componentes del gasto educativo nacional, particularmente las transferencias destinadas a universidades y provincias y a programas de apoyo a estudiantes&#8221;, destac\u00f3 el IIEP.<\/p>\n<p>Seg\u00fan lo proyectado para 2026, de no producirse nuevas ampliaciones de las partidas presupuestarias vigentes, el gasto en esta funci\u00f3n volver\u00eda a registrar un descenso real de 12,7%.<\/p>\n<p>De concretarse este escenario, el presupuesto educativo nacional acumular\u00eda tres a\u00f1os consecutivos con variaciones negativas en t\u00e9rminos reales. Adem\u00e1s, la participaci\u00f3n de Educaci\u00f3n y Cultura tanto en el PBI como dentro del gasto total de la Administraci\u00f3n P\u00fablica Nacional (APN) se ubicar\u00eda en m\u00ednimos desde el inicio de la serio.<\/p>\n<p>Por programas, las transferencias destinadas al financiamiento universitario -a trav\u00e9s del programa Desarrollo de la Educaci\u00f3n Superior- mostraron una merma real de 5,4% interanual en 2025, mientras que las becas estudiantiles se redujeron en un 42,5% y el programa de Gesti\u00f3n Educativa y Pol\u00edticas Socioeducativas baj\u00f3 49,5%.<\/p>\n<p>La principal excepci\u00f3n fue el Plan Nacional de Alfabetizaci\u00f3n, que increment\u00f3 su ejecuci\u00f3n y se convirti\u00f3 en una de las principales l\u00edneas de acci\u00f3n de la Secretar\u00eda de Educaci\u00f3n.<\/p>\n<p><strong>El debate por el financiamiento<\/strong><\/p>\n<p>Otro punto relevante que analiz\u00f3 el IIEP se vincula con los distintos modelos posibles de financiamiento. Hist\u00f3ricamente, se organiz\u00f3 en torno a un esquema orientado principalmente a la oferta, en el que los recursos p\u00fablicos se asignan a los sistemas provinciales y a las instituciones con el objetivo de garantizar infraestructura, cargos docentes y salarios, asegurando condiciones b\u00e1sicas de funcionamiento.<\/p>\n<p>En contraste, la asignaci\u00f3n por demanda se inscribe dentro de los cuasi-mercados educativos, basados en la separaci\u00f3n entre aportes estatales y provisi\u00f3n.<\/p>\n<p>Bajo este enfoque, el Estado puede sostener la educaci\u00f3n con la transferencia de recursos a las familias o estudiantes para que elijan entre distintos proveedores educativos. De este modo, la competencia entre instituciones y la libertad de elecci\u00f3n funcionar\u00edan como mecanismos para mejorar la eficiencia y la calidad del sistema.<\/p>\n<p>Sin embargo, el IIEP considera que es necesario incorporar tambi\u00e9n sus efectos sobre la equidad, la cohesi\u00f3n social y la distribuci\u00f3n territorial de la oferta.<\/p>\n<p>&#8220;En contextos de fuerte desigualdad, los mecanismos de competencia pueden derivar en segmentaci\u00f3n de la matr\u00edcula, debilitamiento de la oferta estatal y ampliaci\u00f3n de brechas preexistentes&#8221;, explic\u00f3 el informe.<\/p>\n<p>El Gobierno promueve la discusi\u00f3n sobre la implementaci\u00f3n de vouchers, becas o transferencias directas a familias, poniendo foco en la libertad de elecci\u00f3n y la competencia entre instituciones. Pero dichas propuestas &#8220;plantean interrogantes respecto de sus posibles efectos sobre la segmentaci\u00f3n social, la desigualdad territorial y la fragmentaci\u00f3n del sistema educativo&#8221;, sostuvieron en la UBA.<\/p>\n<p>En el plano fiscal, indican que un eventual cambio entre ambos modelos no es neutro. Para el IIEP, el financiamiento de la oferta permite orientar recursos seg\u00fan criterios de cobertura territorial y sostenimiento institucional, mientras que el de la demanda traslada parte de las decisiones de asignaci\u00f3n hacia familias y estudiantes. Esto redefine el rol estatal, reduciendo el apoyo a capacidades instaladas y aumentando el subsidio a elecciones individuales.<\/p>\n<p>Recordaron que desde 2024 se aplican vouchers para familias con hijos en escuelas privadas subvencionadas, los cuales alcanzaron a 830.000 estudiantes en 2024 y 504.808 en 2025. &#8220;Esta iniciativa no constituy\u00f3 un sistema generalizado, sino una transferencia focalizada y orientada a cubrir parcialmente el pago de cuotas&#8221;.<\/p>\n<p>&#8220;La implementaci\u00f3n del programa implic\u00f3 un refuerzo a los recursos nacionales destinados a la educaci\u00f3n de gesti\u00f3n privada, en un contexto de desfinanciamiento a la estatal&#8221;, subray\u00f3 el IIEP. En 2023 ya se hab\u00eda habilitado la deducci\u00f3n en Ganancias de gastos escolares privados, beneficio fiscal que favorece a sectores de mayores ingresos.<\/p>\n<p>Asimismo, el proyecto de &#8220;Libertad Educativa&#8221; propone transferencias a instituciones privadas. En la ley vigente, el financiamiento se menciona en el marco de la supervisi\u00f3n y, en ciertos casos, subvenciones, pero sin el mandato de &#8220;regularidad&#8221;.<\/p>\n<p>&#8220;Si bien el objetivo es garantizar el derecho de los padres a optar por una educaci\u00f3n acorde a sus valores, esto implicar\u00eda una nueva v\u00eda de refuerzo al financiamiento de las escuelas privadas en el marco de un retroceso de los recursos para la educaci\u00f3n p\u00fablica. Los cambios podr\u00edan profundizar la segmentaci\u00f3n del sistema y tener efectos desigualadores en el acceso a la educaci\u00f3n de calidad&#8221;, se\u00f1al\u00f3 el IIEP.<\/p>\n<p>Adem\u00e1s, de acuerdo al reporte, el alcance este tipo de pol\u00edticas es muy acotado, ya que la matr\u00edcula se encuentra altamente concentrada en las escuelas p\u00fablicas, excepto en CABA.<\/p>\n<p>&#8220;Podemos decir que estas pol\u00edticas podr\u00edan contribuir a reforzar las desigualdades territoriales existentes en materia de capacidad de financiamiento, ya que algunas de las jurisdicciones donde se concentra la mayor parte de la matr\u00edcula de gesti\u00f3n privada son aquellas con mayor disponibilidad presupuestaria&#8221;, concluy\u00f3 el IIEP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La educaci\u00f3n fue uno de los sectores que m\u00e1s sufri\u00f3 la motosierra desde el inicio de la actual gesti\u00f3n. El debate por los modelos de financiamiento Mientras que las universidades siguen a la espera del cumplimiento de la ley de financiamiento aprobada en el Congreso y ratificada por la Corte Suprema, un estudio de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-9030","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9030"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9030\/revisions"}],"predecessor-version":[{"id":9032,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/9030\/revisions\/9032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/9035"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}