{"id":8969,"date":"2026-07-06T11:58:15","date_gmt":"2026-07-06T14:58:15","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=8969"},"modified":"2026-07-06T11:58:15","modified_gmt":"2026-07-06T14:58:15","slug":"la-policia-detuvo-a-un-delincuente-y-recupero-lo-robado","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/07\/06\/la-policia-detuvo-a-un-delincuente-y-recupero-lo-robado\/","title":{"rendered":"La polic\u00eda detuvo a un delincuente y recuper\u00f3 lo robado"},"content":{"rendered":"<p>La Comisar\u00eda Cuarta de Goya detuvo a un conocido delincuente y recuper\u00f3 objetos robados a pocas horas del hecho. Los efectivos policiales actuaron con extrema rapidez tras recibir la denuncia de un vecino. El operativo cerrojo en la v\u00eda p\u00fablica, a cargo del comisario inspector Miguel Meza, permiti\u00f3 atrapar al sospechoso, alias &#8220;Polaco&#8221;, cuando intentaba vender los elementos sustra\u00eddos.<\/p>\n<p>El hecho comenz\u00f3 a las 06:00 horas del domingo.<\/p>\n<p>Un vecino del barrio, identificado con el apellido Alegre, sufri\u00f3 la inseguridad en su propio domicilio ubicado en Chile al 1200.<\/p>\n<p>Al notar la falta de varios elementos de valor, la v\u00edctima acudi\u00f3 inmediatamente a la comisaria cuarta para radicar la denuncia por supuesto hurto. Los ladrones se hab\u00edan llevado:<\/p>\n<p>Los polic\u00edas salieron a recorrer la jurisdicci\u00f3n con datos precisos sobre el posible sospechoso.<\/p>\n<p>En la intersecci\u00f3n de las calles Catamarca y Rep\u00fablica del L\u00edbano, la patrulla divis\u00f3 al presunto autor del hecho.<\/p>\n<p>El sospechoso fue identificado con el apellido Gonz\u00e1lez, apodado &#8220;Polaco&#8221;. Al momento de la interceptaci\u00f3n, se encontraba acompa\u00f1ado por su primo cuyo apellido ser\u00eda Alcaraz.<\/p>\n<p>Ambos sujetos ten\u00edan en su poder la totalidad de las pertenencias robadas y se dispon\u00edan a comercializarlas en la v\u00eda p\u00fablica. Al verse acorralados por los efectivos de la Comisar\u00eda Cuarta, los hombres no ofrecieron resistencia y realizaron la entrega voluntaria de todos los elementos.<\/p>\n<p>Los polic\u00edas secuestraron una garrafa, una maza y ca\u00f1as de pescar.<\/p>\n<p>Se dio intervenci\u00f3n inmediata a las autoridades judiciales en turno. &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisar\u00eda Cuarta de Goya detuvo a un conocido delincuente y recuper\u00f3 objetos robados a pocas horas del hecho. Los efectivos policiales actuaron con extrema rapidez tras recibir la denuncia de un vecino. El operativo cerrojo en la v\u00eda p\u00fablica, a cargo del comisario inspector Miguel Meza, permiti\u00f3 atrapar al sospechoso, alias &#8220;Polaco&#8221;, cuando intentaba [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-8969","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=8969"}],"version-history":[{"count":2,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8969\/revisions"}],"predecessor-version":[{"id":8972,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8969\/revisions\/8972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/8970"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=8969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=8969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=8969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}