{"id":8208,"date":"2026-06-25T14:07:23","date_gmt":"2026-06-25T17:07:23","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=8208"},"modified":"2026-06-25T14:07:23","modified_gmt":"2026-06-25T17:07:23","slug":"chivos-expiatorios-que-dice-la-carta-de-carlos-perez-en-el-reinicio-del-juicio-por-loan","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/06\/25\/chivos-expiatorios-que-dice-la-carta-de-carlos-perez-en-el-reinicio-del-juicio-por-loan\/","title":{"rendered":"\u201cChivos expiatorios\u201d: qu\u00e9 dice la carta de Carlos P\u00e9rez en el reinicio del juicio por Loan"},"content":{"rendered":"<div>En la antesala de la tercera audiencia del juicio por la desaparici\u00f3n de Loan Pe\u00f1a,\u00a0uno de los imputados,\u00a0Carlos P\u00e9rez,\u00a0le entreg\u00f3 una carta a su abogado defensor, Ernesto \u201cTito\u201d Gonz\u00e1lez,\u00a0con una serie de inquietudes vinculadas al desarrollo del debate oral.<\/div>\n<div><\/div>\n<div>Seg\u00fan explic\u00f3 el letrado en di\u00e1logo con\u00a0TN, el contenido del escrito no apunta a cuestiones personales ni declaraciones de fondo, sino a aspectos estrictamente t\u00e9cnicos del proceso.\u00a0<strong>\u201c<\/strong>La carta son notas, consultas t\u00e9cnicas sobre c\u00f3mo se va a desarrollar el debate. Son cuestiones t\u00e9cnicas. Son inquietudes, y mejor para m\u00ed si me las anota\u201d<strong>,\u00a0<\/strong>detall\u00f3.<\/div>\n<div><\/div>\n<div>\n<p>En las im\u00e1genes a las que accedi\u00f3 este medio se puede leer que el escrito comienza con el t\u00edtulo \u201cChivos expiatorios<strong>\u201d.\u00a0<\/strong>Luego contin\u00faa: \u201cConsidero que este lamentable hecho ocurrido en la provincia de Corrientes\u00a0ha superado ampliamente las capacidades investigativas del orden fiscal&#8221;.<\/p>\n<p>Y sigue:\u00a0<strong>\u201c<\/strong>Tal vez la fuerte presi\u00f3n medi\u00e1tica que inunda la provincia produjo que ante indicios y no pruebas fehacientes r\u00e1pidamente se nos juzgue falsamente\u201d.<\/p>\n<p>El intercambio entre P\u00e9rez y Gonz\u00e1lez se produjo minutos antes del inicio de la nueva audiencia en el\u00a0Escuadr\u00f3n 48 de Gendarmer\u00eda Nacional en Corrientes.Adem\u00e1s de hoy, esta semana habr\u00e1 otra audiencia el jueves, que est\u00e1 prevista para las 9.00.<\/p>\n<h2>Qu\u00e9 se espera esta semana en el juicio por la desaparici\u00f3n de Loan<\/h2>\n<p>Esta semana ser\u00e1 central en el proceso, ya que tanto\u00a0las nulidades que las interpondr\u00e1n las defensascomo las eventuales declaraciones de los imputados\u00a0permitir\u00e1n empezar a reconstruir en detalle lo ocurridoy poner a prueba las hip\u00f3tesis que sostienen las partes.<\/p>\n<p>En este contexto, tambi\u00e9n podr\u00edan presentarse ante el Tribunal Oral Federal (TOF) de Corrientes personas del entorno de Loan,\u00a0como Mar\u00eda y Jos\u00e9, sus pap\u00e1s<strong>,\u00a0<\/strong>que no pudieron declarar la semana anterior.<\/p>\n<p>La audiencia del jueves pasado hab\u00eda sido postergada\u00a0por la ausencia de uno de los imputados (Rossi Colombo) en la jornada inicial\u00a0y por los pedidos de tiempo de la nueva defensa (Juliana Machado) para interiorizarse en el expediente.<\/p>\n<p>Las indagatorias, en tanto, abrir\u00edan la posibilidad de que los acusados den su versi\u00f3n de los hechos o elijan guardar silencio. Tras una primera semana en la que se los vio inquietos y con intenci\u00f3n de hablar,\u00a0crece la expectativa sobre lo que puedan decir.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En la antesala de la tercera audiencia del juicio por la desaparici\u00f3n de Loan Pe\u00f1a,\u00a0uno de los imputados,\u00a0Carlos P\u00e9rez,\u00a0le entreg\u00f3 una carta a su abogado defensor, Ernesto \u201cTito\u201d Gonz\u00e1lez,\u00a0con una serie de inquietudes vinculadas al desarrollo del debate oral. Seg\u00fan explic\u00f3 el letrado en di\u00e1logo con\u00a0TN, el contenido del escrito no apunta a cuestiones personales [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-8208","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=8208"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8208\/revisions"}],"predecessor-version":[{"id":8210,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/8208\/revisions\/8210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/8209"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=8208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=8208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=8208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}