{"id":6647,"date":"2026-05-27T23:12:17","date_gmt":"2026-05-28T02:12:17","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=6647"},"modified":"2026-05-27T23:12:17","modified_gmt":"2026-05-28T02:12:17","slug":"guayquiraro-detectaron-irregularidades-en-el-traslado-de-hacienda-durante-control-policial-sobre-ruta12","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/27\/guayquiraro-detectaron-irregularidades-en-el-traslado-de-hacienda-durante-control-policial-sobre-ruta12\/","title":{"rendered":"GUAYQUIRAR\u00d3: Detectaron irregularidades en el traslado de hacienda durante control policial sobre Ruta12"},"content":{"rendered":"<p>Efectivos policiales dependientes de Goya, demoraron dos camiones jaula con 62 animales bovinos uno y con 61 animales el otro. Detectaron documentaci\u00f3n ilegal.<\/p>\n<div>yer, martes y en el marco de operativos de prevenci\u00f3n y contralor, efectivos policiales de la Unidad especial de Seguridad Vial de Goya, realizaron un procedimiento sobre Ruta Nacional N\u00b0 12, kil\u00f3metro 648, en el puesto de control de Guayquirar\u00f3.<\/div>\n<div><\/div>\n<div>Durante el operativo, los uniformados procedieron a la demora preventiva de dos camiones jaula que transportaban hacienda vacuna. Uno de los rodados trasladaban un total de 62 animales bovinos, mientras que el segundo veh\u00edculo , 61 animales bovinos.<\/div>\n<div><\/div>\n<div>Al momento de la inspecci\u00f3n correspondiente, el personal interviniente detect\u00f3 presuntas irregularidades en las documentaciones y gu\u00edas de traslado de la hacienda, motivo por el cual se solicit\u00f3 colaboraci\u00f3n de sus pares de la Unidad especial de Seguridad rural y ecol\u00f3gica de Esquina.<\/div>\n<div><\/div>\n<div>De todo ello, se puso en conocimiento de las autoridades competentes, continu\u00e1ndose con las diligencias y actuaciones de rigor.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos policiales dependientes de Goya, demoraron dos camiones jaula con 62 animales bovinos uno y con 61 animales el otro. Detectaron documentaci\u00f3n ilegal. yer, martes y en el marco de operativos de prevenci\u00f3n y contralor, efectivos policiales de la Unidad especial de Seguridad Vial de Goya, realizaron un procedimiento sobre Ruta Nacional N\u00b0 12, kil\u00f3metro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-6647","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6647"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6647\/revisions"}],"predecessor-version":[{"id":6650,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6647\/revisions\/6650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/6649"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}