{"id":6598,"date":"2026-05-26T10:58:35","date_gmt":"2026-05-26T13:58:35","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=6598"},"modified":"2026-05-26T10:58:35","modified_gmt":"2026-05-26T13:58:35","slug":"obispo-correntino-participo-en-la-catedral-metropolitana-del-tedeum-donde-la-iglesia-pidio-dialogo-y-reconciliacion","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/26\/obispo-correntino-participo-en-la-catedral-metropolitana-del-tedeum-donde-la-iglesia-pidio-dialogo-y-reconciliacion\/","title":{"rendered":"Obispo correntino particip\u00f3 en la Catedral Metropolitana del Tedeum donde la Iglesia pidi\u00f3 &#8220;di\u00e1logo y reconciliaci\u00f3n&#8221;"},"content":{"rendered":"<p>Acompa\u00f1\u00f3 al arzobispo Jorge Garc\u00eda Cuerva, en la tradicional celebraci\u00f3n que cont\u00f3 con la presencia del presidente de la Naci\u00f3n, Javier Milei, entre los obispos auxiliares de Buenos Aires, monse\u00f1or Iv\u00e1n Dornelles. El prelado correntino oficiar\u00e1 una misa para los comprovincianos en La Plata, este s\u00e1bado 30. La Misa Correntina llegar\u00eda a la Catedral porte\u00f1a el pr\u00f3ximo 19 de septiembre.<\/p>\n<p>En oportunidad de manifestar el reclamo por di\u00e1logo, encuentro y reconciliaci\u00f3n nacional durante el tedeum de la Catedral de Buenos Aires, el arzobispo porte\u00f1o monse\u00f1or Jorge Garc\u00eda Cuerva estuvo acompa\u00f1ado del correntino obispo auxiliar de Buenos Aires Iv\u00e1n Dornelles.<\/p>\n<p>El pedido, y advertencia, fue pronunciado ante el presidente Javier Milei, integrantes del gabinete nacional y el jefe de Gobierno porte\u00f1o, Jorge Macri, entre otras autoridades civiles y militares.<\/p>\n<p>Junto con sus pares obispos auxiliares que secundaron a Garc\u00eda Cuerva en el tradicional tedeum del 25 de Mayo este lunes en la Ciudad Aut\u00f3noma de Buenos Aires, Dornelles particip\u00f3 de la tradicional ceremonia donde la Iglesia llam\u00f3 a construir &#8220;cuatro acuerdos fundamentales&#8221; para la Argentina: el bien com\u00fan, el di\u00e1logo, la amistad social y la esperanza.<\/p>\n<p>Otro de los correntinos presentes fue el ministro de Hacienda y Finanzas del Gobierno de CABA, Gustavo Arengo Piragine, integrante del gabinete a cargo de Macri.<\/p>\n<p>Dornelles es oriundo de\u00a0 la ciudad de General Alvear, sobre la ruta Nacional 14, en el sureste de la provincia de Corrientes.<\/p>\n<p>Misa en La Plata<\/p>\n<p>Por otra parte, este s\u00e1bado 30 de mayo, monse\u00f1or Dornelles celebrar\u00e1 misa en La Plata, capital de la provincia de Buenos Aires, para los residentes correntinos en esta ciudad y del gran Buenos Aires.<\/p>\n<p>La misa se oficiar\u00e1 en la sede del Centro de Residentes Correntinos del Gran La Plata, ubicado en calle 50 N\u00b01629, a partir de las 17.<\/p>\n<p>La oportunidad significar\u00e1 de encuentro para la comunidad correntina, que disfrutar\u00e1n del encuentro con distintas actividades.<\/p>\n<p>Los residentes tambi\u00e9n motorizan la posibilidad que la Misa Correntina, con acordes chamameceros, sea parte de la ceremonia en la Catedral de CABA el s\u00e1bado 19 de septiembre pr\u00f3ximo en el marco del D\u00eda Nacional del Chamam\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompa\u00f1\u00f3 al arzobispo Jorge Garc\u00eda Cuerva, en la tradicional celebraci\u00f3n que cont\u00f3 con la presencia del presidente de la Naci\u00f3n, Javier Milei, entre los obispos auxiliares de Buenos Aires, monse\u00f1or Iv\u00e1n Dornelles. El prelado correntino oficiar\u00e1 una misa para los comprovincianos en La Plata, este s\u00e1bado 30. La Misa Correntina llegar\u00eda a la Catedral porte\u00f1a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-6598","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6598"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6598\/revisions"}],"predecessor-version":[{"id":6600,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6598\/revisions\/6600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/6599"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}