{"id":6292,"date":"2026-05-17T21:49:21","date_gmt":"2026-05-18T00:49:21","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=6292"},"modified":"2026-05-17T21:49:21","modified_gmt":"2026-05-18T00:49:21","slug":"ucrania-lanzo-mas-de-500-drones-contra-moscu-en-el-mayor-ataque-sobre-rusia-en-mas-de-un-ano","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/17\/ucrania-lanzo-mas-de-500-drones-contra-moscu-en-el-mayor-ataque-sobre-rusia-en-mas-de-un-ano\/","title":{"rendered":"Ucrania lanz\u00f3 m\u00e1s de 500 drones contra Mosc\u00fa en el mayor ataque sobre Rusia en m\u00e1s de un a\u00f1o"},"content":{"rendered":"<p>La ofensiva dej\u00f3 muertos, heridos y fuertes da\u00f1os en distintas regiones rusas, en una nueva escalada del conflicto tras recientes bombardeos de Mosc\u00fa sobre Kiev.<\/p>\n<p>Ucrania lanz\u00f3 este fin de semana m\u00e1s de 500 drones contra Mosc\u00fa y otras regiones de Rusia, en lo que las autoridades rusas calificaron como uno de los ataques m\u00e1s graves sufridos en su territorio desde el inicio de la invasi\u00f3n en 2022. El Ministerio de Defensa ruso asegur\u00f3 haber interceptado centenares de aparatos, aunque varios lograron impactar en zonas residenciales de la periferia moscovita, causando da\u00f1os materiales, interrupciones en aeropuertos y escenas de p\u00e1nico entre la poblaci\u00f3n.<\/p>\n<p>Seg\u00fan informaci\u00f3n oficial rusa, al menos cuatro personas murieron y varias resultaron heridas por los impactos. Las autoridades locales difundieron im\u00e1genes y reportes de incendios y destrucci\u00f3n en edificios y v\u00edas de comunicaci\u00f3n, adem\u00e1s de la suspensi\u00f3n temporal de operaciones en aeropuertos cercanos a la capital.<\/p>\n<p title=\"__IP__\" data-ipspy=\"__IP__\">El presidente ucraniano, Volod\u00edmir Zelenski, defendi\u00f3 la operaci\u00f3n como una represalia &#8220;completamente justificada&#8221; ante los recientes bombardeos masivos rusos sobre Kiev y otras ciudades ucranianas, donde en las \u00faltimas semanas se registraron fuertes ataques con misiles y drones contra infraestructura civil y energ\u00e9tica.<\/p>\n<p>El ataque pone de relieve la creciente capacidad de Ucrania para golpear objetivos a cientos de kil\u00f3metros dentro del territorio ruso y marca una nueva fase de escalada militar. Ambos bandos han incrementado el uso de drones como herramienta estrat\u00e9gica, lo que ampl\u00eda la complejidad y el alcance del conflicto con riesgos mayores para la poblaci\u00f3n civil y la infraestructura cr\u00edtica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ofensiva dej\u00f3 muertos, heridos y fuertes da\u00f1os en distintas regiones rusas, en una nueva escalada del conflicto tras recientes bombardeos de Mosc\u00fa sobre Kiev. Ucrania lanz\u00f3 este fin de semana m\u00e1s de 500 drones contra Mosc\u00fa y otras regiones de Rusia, en lo que las autoridades rusas calificaron como uno de los ataques m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-6292","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6292"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6292\/revisions"}],"predecessor-version":[{"id":6294,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6292\/revisions\/6294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/6293"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}