{"id":6178,"date":"2026-05-14T14:02:15","date_gmt":"2026-05-14T17:02:15","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=6178"},"modified":"2026-05-14T14:02:15","modified_gmt":"2026-05-14T17:02:15","slug":"diputado-libertario-llego-al-congreso-en-una-tesla-cybertruck-de-unos-300-mil-dolares","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/14\/diputado-libertario-llego-al-congreso-en-una-tesla-cybertruck-de-unos-300-mil-dolares\/","title":{"rendered":"Diputado libertario lleg\u00f3 al Congreso en una Tesla Cybertruck de unos 300 mil d\u00f3lares"},"content":{"rendered":"<p>La escena gener\u00f3 tensi\u00f3n dentro de La Libertad Avanza y Mart\u00edn Menem le habr\u00eda pedido que retirara el veh\u00edculo del predio.<\/p>\n<div class=\"cuerpo\" data-twitter-link=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.diariopopular.com.ar\/c900136&amp;via=poopulardiario&amp;amp;related=Popular&amp;amp;text=\">\n<p id=\"p-1778756031811-91286\" data-start=\"770\" data-end=\"1019\">Manuel Quintar, diputado nacional de La Libertad Avanza (LLA) por Jujuy, qued\u00f3 en el centro de la pol\u00e9mica luego de llegar al Congreso a bordo de una Tesla Cybertruck, una pick up el\u00e9ctrica valuada en alrededor de 300 mil d\u00f3lares\u00a0en Argentina.<\/p>\n<\/div>\n<div class=\"cuerpo\" data-twitter-link=\"#TWEMBEDLINK#\">\n<p id=\"p-1778756241779-16674\" data-start=\"1023\" data-end=\"1253\">El veh\u00edculo, ploteado con el logo libertario, fue estacionado en la cochera de la C\u00e1mara de Diputados y r\u00e1pidamente se viraliz\u00f3 en redes sociales, donde desat\u00f3 cr\u00edticas de la oposici\u00f3n y tambi\u00e9n incomodidad dentro del oficialismo.<\/p>\n<div class=\"cuerpo\" data-twitter-link=\"#TWEMBEDLINK#\">\n<p id=\"p-1778756031811-67279\" data-start=\"1257\" data-end=\"1411\">El propio Quintar confirm\u00f3 que la camioneta es suya a trav\u00e9s de un mensaje en X:\u00a0<strong data-start=\"1338\" data-end=\"1370\">&#8220;<\/strong>A mi nombre, con la m\u00eda..<strong data-start=\"1338\" data-end=\"1370\">.&#8221;<\/strong>, escribi\u00f3 junto a una foto del veh\u00edculo.<\/p>\n<\/div>\n<div class=\"cuerpo\" data-twitter-link=\"#TWEMBEDLINK#\">\n<p id=\"p-1778756031811-2070\" data-start=\"1415\" data-end=\"1662\">Seg\u00fan trascendi\u00f3 desde el Congreso, el presidente de la C\u00e1mara de Diputados,\u00a0Mart\u00edn Menem, le habr\u00eda pedido al legislador que retirara la Cybertruck del predio luego de que el episodio comenzara a generar ruido interno en el bloque libertario.<\/p>\n<p id=\"p-1778756031811-22529\" data-start=\"1666\" data-end=\"1908\">Desde el entorno del diputado aseguraron que la importaci\u00f3n del veh\u00edculo fue realizada de manera legal y explicaron que la ausencia de patente visible responde a demoras administrativas vinculadas a la entrega de chapas por parte de la DNRPA.<\/p>\n<p id=\"p-1778756031811-94124\" data-start=\"1912\" data-end=\"2094\">&#8220;La compr\u00f3 en Estados Unidos y est\u00e1 todo en regla&#8221;, sostuvieron cerca del legislador, quien adem\u00e1s confirm\u00f3 que se trata de la versi\u00f3n m\u00e1s potente del modelo fabricado por Tesla.<\/p>\n<p id=\"p-1778756031811-41818\" data-start=\"2098\" data-end=\"2405\">La escena se produjo en un contexto especialmente sensible para el Gobierno nacional. Esta semana, la administraci\u00f3n de\u00a0Javier Milei\u00a0avanz\u00f3 con un recorte de casi\u00a02,5 billones de pesos\u00a0en partidas presupuestarias destinadas a distintas \u00e1reas del Estado, como salud, educaci\u00f3n y programas sanitarios.<\/p>\n<p id=\"p-1778756031811-10793\" data-start=\"2409\" data-end=\"2587\">Por eso, desde distintos sectores opositores apuntaron contra el contraste entre el discurso de austeridad libertario y la ostentaci\u00f3n de un veh\u00edculo de lujo dentro del Congreso.<\/p>\n<p id=\"p-1778756507538-38939\" data-start=\"0\" data-end=\"308\">La\u00a0Tesla Cybertruck\u00a0no tiene representaci\u00f3n oficial en la Argentina y las unidades que circulan en el pa\u00eds ingresan mediante importaci\u00f3n privada. Uno de los empresarios vinculados a ese negocio es\u00a0Malek Fara, conocido tambi\u00e9n por traer modelos de Ferrari, Lamborghini, Cadillac Escalade y GMC Hummer.<\/p>\n<p id=\"p-1778756507538-31854\" data-start=\"312\" data-end=\"611\">Seg\u00fan fuentes del sector automotor, hasta el momento ya habr\u00edan ingresado al pa\u00eds unas seis Cybertruck. Aunque\u00a0en Estados Unidos el modelo parte desde los 70 mil d\u00f3lares, los costos de importaci\u00f3n, impuestos y log\u00edstica elevan el valor final en Argentina a cifras cercanas a los\u00a0300 mil d\u00f3lares.<\/p>\n<p id=\"p-1778756507538-55014\" data-start=\"615\" data-end=\"854\" data-is-last-node=\"\" data-is-only-node=\"\">Las unidades que llegaron corresponden a la versi\u00f3n con doble motor el\u00e9ctrico y tracci\u00f3n integral, con una potencia de\u00a0600 caballos, aceleraci\u00f3n de\u00a00 a 100 km\/h en 3,9 segundos\u00a0y una autonom\u00eda declarada de hasta\u00a0550 kil\u00f3metros.<\/p>\n<p id=\"p-1778756031811-10164\" data-start=\"2929\" data-end=\"3199\">Adem\u00e1s de su actividad legislativa, Quintar mantiene un perfil empresario ligado al sector de la salud privada en Jujuy. Seg\u00fan su declaraci\u00f3n jurada, posee tambi\u00e9n veh\u00edculos de alta gama como un Mercedes-Benz, motos KTM y Husqvarna, adem\u00e1s de camionetas Amarok y Toyota.<\/p>\n<p id=\"p-1778756031811-75964\" data-start=\"3203\" data-end=\"3427\">Dentro del universo libertario, el diputado responde pol\u00edticamente al armado de\u00a0Karina Milei\u00a0y mantiene diferencias internas con el senador juje\u00f1o\u00a0Ezequiel Atauche, cercano al asesor presidencial\u00a0Santiago Caputo.<\/p>\n<p id=\"p-1778756031811-86850\" data-start=\"3431\" data-end=\"3642\" data-is-last-node=\"\" data-is-only-node=\"\">En paralelo, en el oficialismo circulan versiones que indican que Quintar buscar\u00eda proyectar su candidatura a gobernador de Jujuy en 2027 y utilizar la Cybertruck como parte de su construcci\u00f3n de imagen p\u00fablica.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La escena gener\u00f3 tensi\u00f3n dentro de La Libertad Avanza y Mart\u00edn Menem le habr\u00eda pedido que retirara el veh\u00edculo del predio. Manuel Quintar, diputado nacional de La Libertad Avanza (LLA) por Jujuy, qued\u00f3 en el centro de la pol\u00e9mica luego de llegar al Congreso a bordo de una Tesla Cybertruck, una pick up el\u00e9ctrica valuada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-6178","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6178"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6178\/revisions"}],"predecessor-version":[{"id":6184,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6178\/revisions\/6184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/6183"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}