{"id":6008,"date":"2026-05-06T16:00:26","date_gmt":"2026-05-06T19:00:26","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=6008"},"modified":"2026-05-06T16:00:26","modified_gmt":"2026-05-06T19:00:26","slug":"gladys-la-bomba-tucumana-amenazo-con-abandonar-gran-hermano","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/06\/gladys-la-bomba-tucumana-amenazo-con-abandonar-gran-hermano\/","title":{"rendered":"Gladys &#8220;La Bomba Tucumana&#8221; amenaz\u00f3 con abandonar Gran Hermano"},"content":{"rendered":"<p>La cantante qued\u00f3 afectada tras un enfrentamiento con Luana Fern\u00e1ndez.<\/p>\n<p>La cantante\u00a0Gladys &#8220;La Bomba Tucumana&#8221;\u00a0qued\u00f3 bajo la lupa luego de expresar sus deseos de abandonar la casa de\u00a0Gran Hermano: Generaci\u00f3n Dorada. Como se pudo ver en las c\u00e1maras 24 hs, la int\u00e9rprete de &#8220;Pollera amarilla&#8221; qued\u00f3 afectada tras protagonizar un enfrentamiento con\u00a0Luana Fern\u00e1ndez.<\/p>\n<div class=\"columns\" data-tadevel-template=\"web\/article-columns\">\n<div class=\"column-main\">\n<div class=\"article-body\" data-tadevel-template=\"web\/article-body\">\n<div class=\"article-body-content\">\n<p>El conflicto, adem\u00e1s, tiene como protagonista a\u00a0Franco Zunino, ya que, seg\u00fan se supo, ambas demostraron su inter\u00e9s rom\u00e1ntico en el participante.<\/p>\n<p>En esta oportunidad, la cantante expres\u00f3 su enojo por un comentario malintencionado que la joven le hizo en una charla que no trascendi\u00f3 a las redes. En dicho intercambio, Luana habr\u00eda hecho una fuerte acusaci\u00f3n en contra de ella, sosteniendo que entr\u00f3 solo para &#8220;robarse&#8221; a Zunino y molestarla.<\/p>\n<p>&#8220;Si yo te digo as\u00ed, es feo. Tal vez algunas personas puedan soportarlo y yo no, porque no tengo necesidad. Tengo 60 a\u00f1os, una vida y una carrera hechas, una familia. Ustedes son jovencitas\u2026&#8221;, le dec\u00eda a Cinzia.<\/p>\n<p>&#8220;Grave es que alguien te diga: \u2018Vos sos una prostituta y viniste ac\u00e1 a sacarme mi marido\u2019. \u00bfA una se\u00f1ora de 60 a\u00f1os? Yo no la disculpo una mierda&#8230; y no me interesa nada&#8221;, continu\u00f3.<\/p>\n<p title=\"__IP__\" data-ipspy=\"__IP__\">Gladys dej\u00f3 en claro que no tolerar\u00eda dichas situaciones y amenaz\u00f3 con abandonar la competencia si Luana insist\u00eda con su postura: &#8220;Si no, yo no quiero saber nada con nadie y me quisiera ir. Entro a decirle al p\u00fablico que me vote para que me vaya; yo no pienso estar renegando, no me gusta y no tengo necesidad. Tengo 60 a\u00f1os, una vida y una carrera hechas&#8221;.<\/p>\n<p>Teniendo en cuenta que Gran Hermano no tolera m\u00e1s &#8220;las amenazas&#8221; de sus hu\u00e9spedes, a\u00fan se espera que el Big reaccione a las declaraciones de la cantante.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cantante qued\u00f3 afectada tras un enfrentamiento con Luana Fern\u00e1ndez. La cantante\u00a0Gladys &#8220;La Bomba Tucumana&#8221;\u00a0qued\u00f3 bajo la lupa luego de expresar sus deseos de abandonar la casa de\u00a0Gran Hermano: Generaci\u00f3n Dorada. Como se pudo ver en las c\u00e1maras 24 hs, la int\u00e9rprete de &#8220;Pollera amarilla&#8221; qued\u00f3 afectada tras protagonizar un enfrentamiento con\u00a0Luana Fern\u00e1ndez. El conflicto, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[],"class_list":["post-6008","post","type-post","status-publish","format-standard","has-post-thumbnail","category-espectaculo"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6008"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6008\/revisions"}],"predecessor-version":[{"id":6010,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/6008\/revisions\/6010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/6009"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}