{"id":5904,"date":"2026-05-01T17:14:06","date_gmt":"2026-05-01T20:14:06","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=5904"},"modified":"2026-05-01T17:14:06","modified_gmt":"2026-05-01T20:14:06","slug":"la-noche-de-pena-de-pescadores-brillo-con-chamame-alegria-y-mucho-color","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/05\/01\/la-noche-de-pena-de-pescadores-brillo-con-chamame-alegria-y-mucho-color\/","title":{"rendered":"La noche de pe\u00f1a de pescadores brill\u00f3 con chamam\u00e9, alegr\u00eda y mucho color"},"content":{"rendered":"<p>La segunda jornada de la\u00a0<strong>49\u00b0 Fiesta Nacional del Surubi<\/strong>\u00a0estuvo marcado por el fraternal encuentro, en la Pe\u00f1a de Pescadores. Es un momento \u00fanico dentro de la magnitud de la fiesta, donde lo esencial cobra sentido. All\u00ed, entre brindis y recuerdos, se reafirma que ser pescador no es solo una actividad, sino una forma de vida que se celebra, se comparte y, sobre todo, se siente profundamente. A ello se suma vivirlo a lo grande, con artistas chamameceros de primer nivel y una noche que quedar\u00e1 para siempre.<\/p>\n<p>La segunda noche del Escenario Mayor \u201cJuan Melero\u201d en la\u00a049\u00b0 Fiesta Nacional del Surubi, se vivi\u00f3 como una verdadera celebraci\u00f3n de la identidad litorale\u00f1a, con el chamam\u00e9 como bandera y el coraz\u00f3n del p\u00fablico latiendo al ritmo de cada acorde.<\/p>\n<p>El inicio art\u00edstico lo realiz\u00f3 el Ballet de Ra\u00fal Ch\u00e1vez, que despleg\u00f3 sobre el escenario toda la fuerza expresiva de la danza folkl\u00f3rica.<\/p>\n<p>Y la m\u00fasica sigui\u00f3 en la noche de los pescadores: y su ritmo comenz\u00f3 a fluir con artistas que representan lo mejor de nuestra cultura. Federico Maceri aport\u00f3 su estilo y sensibilidad, conectando con el p\u00fablico desde la interpretaci\u00f3n y el sentimiento.<\/p>\n<p>A su turno, Paula Basalo sum\u00f3 su inconfundible voz a la noche, y reafirmando el protagonismo femenino dentro del g\u00e9nero.<\/p>\n<p>El momento fue creciendo en intensidad con el anuncio del inicio musical de la Pe\u00f1a del Surub\u00ed, un momento que acompa\u00f1\u00f3 al sector gastron\u00f3mico bajo un clima de absoluta algarab\u00eda.<\/p>\n<p>La energ\u00eda se adue\u00f1\u00f3 de los corazones Goyanos cuando escucharon los primeros acordes de Ambo\u00e9. Con su estilo inconfundible y su conexi\u00f3n directa con el p\u00fablico, hicieron vibrar a todos, generando ese clima festivo donde nadie se queda quieto.<\/p>\n<p>La tradici\u00f3n continu\u00f3 con la presencia de Los Bofill, herederos de una historia musical profundamente arraigada en nuestro litoral. Su actuaci\u00f3n reafirm\u00f3 el valor de las ra\u00edces y el legado chamamecero que se transmite de generaci\u00f3n en generaci\u00f3n.<\/p>\n<p>En una nueva visita a Goya, los Alonsitos, llevaron al p\u00fablico por un recorrido vibrante a trav\u00e9s de sus cl\u00e1sicos. Sus canciones fueron coreadas por una multitud que acompa\u00f1\u00f3 cada verso con pasi\u00f3n.<\/p>\n<p>Uno de los momentos m\u00e1s destacados fue la presentaci\u00f3n de Hugo \u201cSc\u00f3fano\u201d de Amanday\u00e9, quien aport\u00f3 toda su experiencia y carisma, conectando con el p\u00fablico desde la autenticidad.<\/p>\n<p>Pedro R\u00edos tambi\u00e9n sum\u00f3 su huella en el escenario, sumando su talento a una grilla cargada de identidad y Diego Guti\u00e9rrez, con una presentaci\u00f3n s\u00f3lida, manteniendo en alto la energ\u00eda y dejando en claro que el chamam\u00e9 sigue m\u00e1s vigente que nunca.<\/p>\n<p>Bocha Sheridan, referente indiscutido del g\u00e9nero, fue otro de los grandes protagonistas de la noche. Su m\u00fasica, cargada de historia y sentimiento, gener\u00f3 un profundo reconocimiento del p\u00fablico, que respondi\u00f3 con aplausos y emoci\u00f3n.<\/p>\n<p>As\u00ed, la segunda noche del Escenario Mayor se consolid\u00f3 como un verdadero homenaje a nuestras ra\u00edces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La segunda jornada de la\u00a049\u00b0 Fiesta Nacional del Surubi\u00a0estuvo marcado por el fraternal encuentro, en la Pe\u00f1a de Pescadores. Es un momento \u00fanico dentro de la magnitud de la fiesta, donde lo esencial cobra sentido. All\u00ed, entre brindis y recuerdos, se reafirma que ser pescador no es solo una actividad, sino una forma de vida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-5904","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=5904"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5904\/revisions"}],"predecessor-version":[{"id":5906,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5904\/revisions\/5906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/5905"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=5904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=5904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=5904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}