{"id":5527,"date":"2026-04-18T11:22:25","date_gmt":"2026-04-18T14:22:25","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=5527"},"modified":"2026-04-18T11:22:25","modified_gmt":"2026-04-18T14:22:25","slug":"iran-volvio-a-cerrar-el-estrecho-de-ormuz-en-respuesta-al-bloqueo-de-estados-unidos","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/04\/18\/iran-volvio-a-cerrar-el-estrecho-de-ormuz-en-respuesta-al-bloqueo-de-estados-unidos\/","title":{"rendered":"Ir\u00e1n volvi\u00f3 a cerrar el estrecho de Ormuz en respuesta al bloqueo de Estados Unidos"},"content":{"rendered":"<p>El Presidente del Parlamento iran\u00ed asegur\u00f3 que el paso se encuentra bajo una estricta gesti\u00f3n militar y acus\u00f3 a Donald Trump de mentir en sus afirmaciones.<\/p>\n<p>Este s\u00e1bado, el Gobierno iran\u00ed inform\u00f3 que cerr\u00f3 nuevamente el estrecho de Ormuz e impuso un &#8220;control estricto&#8221; en el paso. La medida se da horas despu\u00e9s del anuncio de reapertura y en respuesta al bloqueo que mantiene Estados Unidos contra los puertos iran\u00edes.<\/p>\n<p>&#8220;El control del estrecho de Ormuz ha vuelto a su estado anterior y esta v\u00eda estrat\u00e9gica se encuentra bajo una estricta gesti\u00f3n y control por parte de las Fuerzas Armadas&#8221; asegur\u00f3 el portavoz del Cuartel General Central Jatam al Anbiya, el teniente coronel Ebrahim Zolfagari en un comunicado.<\/p>\n<p>Seg\u00fan detall\u00f3 la agencia EFE, el funcionario asegur\u00f3 que Teher\u00e1n permiti\u00f3 nuevamente el paso &#8220;limitado y gestionado&#8221; de algunos buques, mientras duraran las negociaciones por la paz. Sin embargo, tras el anuncio de Donald Trump de continuar con los bloqueos contra Ir\u00e1n, el Gobierno iran\u00ed impuso nuevamente la restricci\u00f3n en Ormuz, y denunci\u00f3 reiterados incumplimientos por parte de Washington.<\/p>\n<p>&#8220;Mientras Estados Unidos no restablezca la plena libertad de tr\u00e1nsito de las embarcaciones desde Ir\u00e1n y hacia Ir\u00e1n, la situaci\u00f3n en el estrecho de Ormuz permanecer\u00e1 bajo un control riguroso&#8221;, sostuvo Zolfagari.<\/p>\n<p><strong>El l\u00edder iran\u00ed apunt\u00f3 contra Trump<\/strong><\/p>\n<p>Tras las medidas anunciadas por Estados Unidos, el presidente del parlamento iran\u00ed, Mohammad Baqer Qalibaf, apunt\u00f3 contra Donald Trump y lo acus\u00f3 de mentir en sus palabras. &#8220;El presidente de los Estados Unidos hizo siete afirmaciones en una hora, todas falsas&#8221;, expres\u00f3 el mandatario en su cuenta de X.<\/p>\n<p>l respecto, Qalibaf critic\u00f3 al Gobierno estadounidense y asegur\u00f3 las medidas que se tomar\u00e1n si el bloqueo continua. &#8220;No ganaron la guerra con esas mentiras, y ciertamente tampoco lograr\u00e1n nada en las negociaciones. Con la continuaci\u00f3n del bloqueo, el estrecho de Ormuz no permanecer\u00e1 abierto&#8221;, se\u00f1al\u00f3<\/p>\n<p>Asimismo, el l\u00edder iran\u00ed asegur\u00f3 que la apertura o el cierre del estrecho, por donde transita el 20% del petr\u00f3leo mundial, estar\u00e1n determinadas por &#8220;la realidad sobre el terreno, no por las redes sociales&#8221;<\/p>\n<p><strong>Bloqueos de Estados Unidos a Ir\u00e1n<\/strong><\/p>\n<p>El Comando Central estadounidense afirm\u00f3 este viernes que mantiene el bloqueo a barcos y puertos iran\u00edes en el estrecho de Ormuz, por orden del presidente Donald Trump. La medida continuar\u00e1 vigente hasta que se logre un acuerdo de paz sobre el conflicto en Medio Oriente.<\/p>\n<p>Seg\u00fan detall\u00f3 la Agencia Noticias Argentinas, el gobierno de Estados Unidos despleg\u00f3 el mayor portaviones del mundo en el mar Rojo para impedir un bloqueo iran\u00ed al tr\u00e1nsito de buques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente del Parlamento iran\u00ed asegur\u00f3 que el paso se encuentra bajo una estricta gesti\u00f3n militar y acus\u00f3 a Donald Trump de mentir en sus afirmaciones. Este s\u00e1bado, el Gobierno iran\u00ed inform\u00f3 que cerr\u00f3 nuevamente el estrecho de Ormuz e impuso un &#8220;control estricto&#8221; en el paso. La medida se da horas despu\u00e9s del anuncio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-5527","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=5527"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5527\/revisions"}],"predecessor-version":[{"id":5529,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5527\/revisions\/5529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/5528"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=5527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=5527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=5527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}