{"id":5497,"date":"2026-04-17T20:08:45","date_gmt":"2026-04-17T23:08:45","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=5497"},"modified":"2026-04-17T20:08:45","modified_gmt":"2026-04-17T23:08:45","slug":"milei-autorizo-el-ingreso-de-fuerzas-armadas-estadounidenses-al-pais-para-ejercicios-militares","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/04\/17\/milei-autorizo-el-ingreso-de-fuerzas-armadas-estadounidenses-al-pais-para-ejercicios-militares\/","title":{"rendered":"Milei autoriz\u00f3 el ingreso de fuerzas armadas estadounidenses al pa\u00eds para ejercicios militares"},"content":{"rendered":"<p>Se trata de una serie de pruebas combinadas entre ambos pa\u00edses que se llevar\u00e1n a cabo en territorio argentino entre abril y junio.<\/p>\n<p>El Gobierno autoriz\u00f3 el ingreso de medios y personal de las Fuerzas Armadas de Estados Unidos para llevar a cabo dos ejercicios conjuntos y combinados entre ambos pa\u00edses en espacios destinados para instrucci\u00f3n militar y en la Zona Econ\u00f3mica Exclusiva.<\/p>\n<p>La autorizaci\u00f3n fue oficializada por decreto este viernes en el Bolet\u00edn Oficial, donde se enumeraron las especificaciones respecto a ambos ejercicios militares que llevar\u00e1n en conjunto las Fuerzas Armadas de Argentina y Estados Unidos.<\/p>\n<p><strong>C\u00f3mo ser\u00e1n los ejercicios entre el Ej\u00e9rcito Argentino y Estados Unidos<\/strong><\/p>\n<p>En el caso del ejercicio &#8220;Daga Atl\u00e1ntica&#8221;, se desarrollar\u00e1 desde el 21 de abril hasta el 12 de junio de 2026 con actividades en la Base Naval Puerto Belgrano, la Guarnici\u00f3n Militar C\u00f3rdoba y la VII Brigada A\u00e9rea de la Fuerza A\u00e9rea Argentina, ubicada en el partido de Moreno, provincia de Buenos Aires.<\/p>\n<p>Se trata de un adiestramiento conjunto y combinado del cual participar\u00e1n 150 efectivos del Ej\u00e9rcito, la Armada y la Fuerza A\u00e9rea Argentina y solo 50 de Estados Unidos.<\/p>\n<p>El objetivo es fortalecer la cooperaci\u00f3n militar dentro del continente, la confianza mutua, la integraci\u00f3n e interoperabilidad entre las Unidades de Fuerzas de Operaciones Especiales del Comando Conjunto de Operaciones Especiales (CCOE) y del Comando Sur de Operaciones Especiales (SOCSOUTH).<\/p>\n<p>El ejercicio busca que las Fuerzas Armadas argentinas mejoren su preparaci\u00f3n trabajando junto a otros pa\u00edses, especialmente con Estados Unidos, para adquirir experiencia en la planificaci\u00f3n, coordinaci\u00f3n, conducci\u00f3n y sincronizaci\u00f3n, as\u00ed como tambi\u00e9n en llevar adelante operaciones especiales de manera coordinada. Esto permite ganar experiencia real y actuar de forma m\u00e1s organizada ante posibles conflictos futuros.<\/p>\n<p>Por otro lado, el ejercicio combinado binacional de Adiestramiento en el Mar &#8220;PASSEX&#8221; se realizar\u00e1 en la Zona Econ\u00f3mica Exclusiva de Argentina entre los d\u00edas 26 y 30 de abril de 2026.<\/p>\n<p>En esta oportunidad, contar\u00e1 con la participaci\u00f3n del portaaviones USS Nimitz y el destructor USS Gridley de la Armada de Estados Unidos.<\/p>\n<p>En este caso, se entrenan maniobras y t\u00e9cnicas navales b\u00e1sicas para mejorar el trabajo en conjunto, fortalecer la confianza entre fuerzas y asegurar que todo se haga dentro de las normas legales vigentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una serie de pruebas combinadas entre ambos pa\u00edses que se llevar\u00e1n a cabo en territorio argentino entre abril y junio. El Gobierno autoriz\u00f3 el ingreso de medios y personal de las Fuerzas Armadas de Estados Unidos para llevar a cabo dos ejercicios conjuntos y combinados entre ambos pa\u00edses en espacios destinados para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-5497","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=5497"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5497\/revisions"}],"predecessor-version":[{"id":5499,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/5497\/revisions\/5499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/5498"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=5497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=5497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=5497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}