{"id":4983,"date":"2026-03-28T15:09:54","date_gmt":"2026-03-28T18:09:54","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=4983"},"modified":"2026-03-28T15:09:54","modified_gmt":"2026-03-28T18:09:54","slug":"argentina-logro-un-deslucido-triunfo-frente-a-mauritania","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/03\/28\/argentina-logro-un-deslucido-triunfo-frente-a-mauritania\/","title":{"rendered":"Argentina logr\u00f3 un deslucido triunfo frente a Mauritania"},"content":{"rendered":"<p>La albiceleste gan\u00f3 2 a 1. Messi ingres\u00f3 en el segundo tiempo y sobre el final del encuentro lo hizo el correntino Jos\u00e9 Manuel L\u00f3pez.<\/p>\n<p>a selecci\u00f3n argentina venci\u00f3 2-1 a Mauritania en la Bombonera en la primera prueba de esta fecha FIFA. Enzo Fern\u00e1ndez y Nico Paz anotaron los goles de la Albiceleste en el primer tiempo, mientras que Lionel Messi fue suplente y jug\u00f3 todo el segundo tiempo.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P1_cuerpo\">\n<div id=\"pppSlot8\" class=\" lazyloaded\" data-gpt=\"\/22675780113\/nota\/new_p1_cuerpo\" data-size=\"[[728, 90]]\" data-gpt-mobile=\"\/22675780113\/nota\/new_p1_cuerpo\" data-size-mobile=\"[[320, 100],[300, 250],[300, 100],[300, 50]]\" data-expand=\"300\" data-google-query-id=\"CO_9qeqXw5MDFYg9uQYdtIQ1NA\">\n<div id=\"google_ads_iframe_\/22675780113\/nota\/new_p1_cuerpo_0__container__\">\n<div id=\"aries_div_4332982181\" class=\"aries_div\">\n<div id=\"banner_list_13028\">En una noche lluviosa y una Bombonera que no se llen\u00f3, el entrenador Lionel Scaloni realiz\u00f3 varias modificaciones para probar variantes frente a un rival que en el segundo tiempo mejor\u00f3 y hasta encontr\u00f3 el descuento gracias a un flojo papel del elenco local.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>El entrenador argentino utiliz\u00f3 los ocho cambios permitidos para darles rodaje a diferentes futbolistas, entre ellos Gabriel Rojas, Agust\u00edn Giay, Franco Mastantuono y el correntino Jos\u00e9 L\u00f3pez. A partir de eso, la Celeste y Blanca se repleg\u00f3 m\u00e1s en la cancha ante un rival que tuvo m\u00e1s oportunidades, pero sufri\u00f3 la ineficacia en carne propia. Sobre el final, logr\u00f3 el descuento a trav\u00e9s del zaguero central Jordan Lefort.<\/p>\n<p>El campe\u00f3n del mundo volver\u00e1 a jugar este martes desde las 20:15 en el recinto de Boca Juniors ante Zambia en el \u00faltimo amistoso de esta ventana de partidos.<\/p>\n<p>El primer gol de la Albiceleste lleg\u00f3 a los 17 minutos, cuando Fern\u00e1ndez conect\u00f3 dentro del \u00e1rea para definir muy c\u00f3modo luego de un gran buscapi\u00e9 del lateral derecho Nahuel Molina, quien se encuentra en un muy buen momento. Solo 15 minutos despu\u00e9s, Nico Paz estir\u00f3 la ventaja con un muy buen tiro libre para convertir su primer con la Selecci\u00f3n Argentina.<\/p>\n<p>El primer tiempo fue un mon\u00f3logo de la Argentina, que domin\u00f3 el desarrollo del juego en todo momento y gener\u00f3 varias situaciones para irse al descanso con un resultado m\u00e1s abultado.<\/p>\n<p>Para el inicio del complemento se dio el ingreso de Messi, Rodrigo de Paul y Franco Mastantuono. Aunque, contra todo pron\u00f3stico, el nivel del equipo argentino cay\u00f3 y le dio espacios a Mauritania para generar numerosas situaciones de peligro.<\/p>\n<p>El merecido descuento del combinado del pa\u00eds africano lleg\u00f3 en la \u00faltima jugada del partido, cuando Lefort se encontr\u00f3 solo con la pelota en el \u00e1rea chica y pudo convertir un gol que recordar\u00e1 para toda su vida.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La albiceleste gan\u00f3 2 a 1. Messi ingres\u00f3 en el segundo tiempo y sobre el final del encuentro lo hizo el correntino Jos\u00e9 Manuel L\u00f3pez. a selecci\u00f3n argentina venci\u00f3 2-1 a Mauritania en la Bombonera en la primera prueba de esta fecha FIFA. Enzo Fern\u00e1ndez y Nico Paz anotaron los goles de la Albiceleste en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-4983","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=4983"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4983\/revisions"}],"predecessor-version":[{"id":4985,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4983\/revisions\/4985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/4984"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=4983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=4983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=4983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}