{"id":4834,"date":"2026-03-21T17:15:55","date_gmt":"2026-03-21T20:15:55","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=4834"},"modified":"2026-03-21T17:15:55","modified_gmt":"2026-03-21T20:15:55","slug":"detectaron-casos-de-tos-convulsa-y-piden-cumplir-con-la-vacunacion","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/03\/21\/detectaron-casos-de-tos-convulsa-y-piden-cumplir-con-la-vacunacion\/","title":{"rendered":"Detectaron casos de tos convulsa y piden cumplir con la vacunaci\u00f3n"},"content":{"rendered":"<p>Los positivos son un beb\u00e9 y dos adultos. El lactante, de tres meses, permanece internado y los mayores cursan la enfermedad sin complicaciones. Desde Salud P\u00fablica informaron que activaron protocolos de control y seguimiento de posibles contactos.<\/p>\n<p>El Ministerio de Salud P\u00fablica de la Provincia inform\u00f3 la detecci\u00f3n de tres casos de tos convulsa o coqueluche, lo que activ\u00f3 un operativo sanitario de vigilancia y control. El caso m\u00e1s relevante corresponde a un beb\u00e9 de tres meses, oriundo del interior, que se encuentra internado en el Hospital Juan Pablo II, mientras que otros dos contagios fueron confirmados en adultos que no requirieron hospitalizaci\u00f3n.<\/p>\n<p>La directora de Epidemiolog\u00eda, Angelina Bobadilla, precis\u00f3 que &#8220;las muestras fueron analizadas en el Laboratorio Central y dieron positivo&#8221;. En ese sentido, llev\u00f3 tranquilidad al se\u00f1alar que todos los pacientes presentan buena evoluci\u00f3n. El ni\u00f1o permanece en sala del hospital pedi\u00e1trico tras haber sido derivado desde un centro de salud del interior provincial.<\/p>\n<h2>Rastrillaje<\/h2>\n<p>Ante la confirmaci\u00f3n de los casos, se desplegaron las acciones habituales de control de brote. Estas incluyen la b\u00fasqueda activa de personas que hayan tenido contacto con los pacientes durante los \u00faltimos 21 d\u00edas, as\u00ed como el monitoreo de sus esquemas de vacunaci\u00f3n.<\/p>\n<p>&#8220;Se est\u00e1n completando dosis en caso de ser necesario&#8221;, explic\u00f3 Bobadilla, quien adem\u00e1s destac\u00f3 el trabajo coordinado entre las \u00e1reas de Inmunizaciones, Vigilancia Epidemiol\u00f3gica provincial y los equipos sanitarios locales.<\/p>\n<p>La tos convulsa, tambi\u00e9n conocida como coqueluche, es una infecci\u00f3n respiratoria altamente contagiosa causada por la bacteria Bordetella pertussis. En sus primeras etapas puede confundirse con un resfr\u00edo com\u00fan, pero con el paso de los d\u00edas la tos se intensifica y puede derivar en cuadros m\u00e1s severos.<\/p>\n<p>Entre los s\u00edntomas m\u00e1s frecuentes se encuentran secreci\u00f3n nasal, congesti\u00f3n, ojos enrojecidos, fiebre leve y episodios de tos persistente que pueden agravarse con el tiempo. En los casos m\u00e1s complejos, la enfermedad puede provocar dificultad para respirar, v\u00f3mitos y un marcado agotamiento.<\/p>\n<h2>Los m\u00e1s afectados<\/h2>\n<p>Esta patolog\u00eda afecta con mayor frecuencia a ni\u00f1os menores de cinco a\u00f1os, especialmente a los lactantes, quienes presentan mayor riesgo de complicaciones.<\/p>\n<p>En este punto, Bobadilla remarc\u00f3 que si bien la enfermedad tiene tratamiento, no est\u00e1 exenta de riesgos: &#8220;Tiene tratamiento antibi\u00f3tico, se cura, pero puede haber complicaciones en pacientes inmunocomprometidos, ya sea por edad o por patolog\u00eda, desde complicaciones como neumon\u00edas a patolog\u00edas generales como una encefalitis&#8221;.<\/p>\n<p>Por este motivo, las autoridades sanitarias insisten en la importancia de la prevenci\u00f3n a trav\u00e9s de la vacunaci\u00f3n.<\/p>\n<h2>Vacunaci\u00f3n en embarazadas<\/h2>\n<p>El esquema de inmunizaci\u00f3n est\u00e1 contemplado en el Calendario Nacional Obligatorio e incluye dosis a los 2, 4 y 6 meses de vida (a trav\u00e9s de la vacuna qu\u00edntuple) con refuerzos al a\u00f1o, a los 15 meses, al ingreso escolar y a los 11 a\u00f1os.<\/p>\n<p>Desde el \u00e1rea de Epidemiolog\u00eda remarcaron que una de las estrategias m\u00e1s efectivas es la vacunaci\u00f3n de las mujeres embarazadas en cada gestaci\u00f3n. Esta medida permite transferir anticuerpos al beb\u00e9 antes del nacimiento, brind\u00e1ndole protecci\u00f3n durante los primeros meses de vida, cuando a\u00fan no complet\u00f3 su esquema de vacunas.<\/p>\n<p>En este contexto, Salud P\u00fablica reiter\u00f3 el llamado a la poblaci\u00f3n a mantener al d\u00eda las vacunas, una herramienta fundamental para prevenir la propagaci\u00f3n de enfermedades y proteger especialmente a los grupos m\u00e1s vulnerables.<\/p>\n<h2>En el pa\u00eds<\/h2>\n<p>El Bolet\u00edn Epidemiol\u00f3gico Nacional dio cuenta de que cursadas las primeras 9 semanas del a\u00f1o fueron detectados ya 215 casos de tos convulsa o coqueluche, con una incidencia acumulada de 0,46 por cada 100.000 habitantes. Si bien estos datos a\u00fan superan las cifras observadas para el mismo per\u00edodo de a\u00f1os anteriores, la tendencia general de las \u00faltimas semanas muestra una disminuci\u00f3n respecto al cierre de 2025.<\/p>\n<p>Explicaron que esta patolog\u00eda presenta un comportamiento c\u00edclico, con picos epid\u00e9micos que ocurren habitualmente cada 3 a 5 a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los positivos son un beb\u00e9 y dos adultos. El lactante, de tres meses, permanece internado y los mayores cursan la enfermedad sin complicaciones. Desde Salud P\u00fablica informaron que activaron protocolos de control y seguimiento de posibles contactos. El Ministerio de Salud P\u00fablica de la Provincia inform\u00f3 la detecci\u00f3n de tres casos de tos convulsa o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-4834","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salud"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=4834"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4834\/revisions"}],"predecessor-version":[{"id":4836,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4834\/revisions\/4836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/4835"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=4834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=4834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=4834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}