{"id":4701,"date":"2026-03-09T12:22:48","date_gmt":"2026-03-09T15:22:48","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=4701"},"modified":"2026-03-09T12:22:48","modified_gmt":"2026-03-09T15:22:48","slug":"las-ventas-pymes-siguen-sin-repuntar-y-en-febrero-cayeron-seis-de-los-siete-rubros","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2026\/03\/09\/las-ventas-pymes-siguen-sin-repuntar-y-en-febrero-cayeron-seis-de-los-siete-rubros\/","title":{"rendered":"Las ventas pymes siguen sin repuntar y en febrero cayeron seis de los siete rubros"},"content":{"rendered":"<p>Lo se\u00f1al\u00f3 el relevamiento publicado por CAME. El desplome fue del 5,6% interanual, por lo que las ventas minoristas pymes llevan diez meses consecutivos en retroceso. El desempe\u00f1o de cada sector.<\/p>\n<p>Las ventas minoristas de las pymes retrocedieron el 5,6% interanual en febrero y cayeron por d\u00e9cimo mes consecutivo. As\u00ed, acumularon un desplome del 5,2% en el primer bimestre del a\u00f1o, de acuerdo con un relevamiento publicado por la Confederaci\u00f3n Argentina de la Mediana Empresa (CAME).<\/p>\n<p>El dato implica un nuevo descenso tras la baja del 4,8% de enero, 5,2% en diciembre, 4,1% en noviembre, 1,4% en octubre, 4,2% en septiembre, 2,6% en agosto, 2% en julio, 0,5% en junio y 2,9% en mayo, cuando se cort\u00f3 con cinco meses de mediciones positivas. En la comparaci\u00f3n mensual desestacionalizada, el \u00cdndice de Ventas Minoristas Pymes registr\u00f3 un repunte en el consumo del 2,6% en el segundo mes del a\u00f1o frente a enero. Ese n\u00famero no pudo revertir el total de la baja en el mes inaugural de 2026 (-4,2%).<\/p>\n<p>Al analizar el escenario, desde CAME sostuvieron que &#8220;febrero registr\u00f3 una mejora mensual del 2,6%, influenciada por el inicio del ciclo lectivo, sin lograr revertir la ca\u00edda acumulada del 5,2%&#8221;. Tambi\u00e9n precisaron que &#8220;el consumo se concentr\u00f3 en bienes de subsistencia y art\u00edculos escolares por la reasignaci\u00f3n del gasto de los hogares&#8221;.<\/p>\n<p>En este sentido, puntualizaron que &#8220;la demanda oper\u00f3 con selectividad, priorizando ofertas y financiamiento para sostener las operaciones&#8221;. Destacaron que &#8220;los costos operativos y la presi\u00f3n tributaria condicionaron la rentabilidad de los locales&#8221; y se\u00f1alaron &#8220;una contracci\u00f3n t\u00e9cnica pese al repunte estacional de fin de mes&#8221;.<\/p>\n<p>En cuanto a la situaci\u00f3n econ\u00f3mica de los comercios, el relevamiento arroj\u00f3 que &#8220;el 52,6% de los propietarios report\u00f3 estabilidad interanual, cifra inferior en seis puntos al registro de enero&#8221; y agreg\u00f3 que &#8220;dicho margen se traslad\u00f3 a quienes se\u00f1alaron un deterioro (38,8%) en comparaci\u00f3n con el mismo per\u00edodo del ciclo anterior&#8221;. Sobre la inversi\u00f3n, el reporte arroj\u00f3 que &#8220;el 57,6% considera el marco como no apto para desembolsos, frente a un 15,5% que lo ve de forma oportuna y un 26,9% sin definici\u00f3n&#8221;.<\/p>\n<p>Con este panorama, desde CAME afirmaron que &#8220;el desaf\u00edo reside en estabilizar los m\u00e1rgenes frente al incremento de los gastos fijos&#8221; y concluyeron que &#8220;la reactivaci\u00f3n depender\u00e1 de la recomposici\u00f3n de los salarios y de la previsibilidad en los costos&#8221;.<\/p>\n<h2>Ventas minoristas pymes: el rendimiento de cada rubro en febrero<\/h2>\n<p>-Alimentos y bebidas: las ventas bajaron un 8,7% en la comparaci\u00f3n interanual, a precios constantes, y acumulan un descenso del 7,4% en lo que va del a\u00f1o. En la comparaci\u00f3n intermensual desestacionalizada, se registr\u00f3 una mejora del 1,4%.<\/p>\n<p>-Bazar, decoraci\u00f3n, textiles para el hogar y muebles: las ventas bajaron 14,4% interanual en febrero, y suman un retroceso del 15,6% en lo que va del a\u00f1o. En el contraste intermensual desestacionalizado, se observ\u00f3 una disminuci\u00f3n del 2,0%.<\/p>\n<p>-Calzado y marroquiner\u00eda: las ventas descendieron un 1,1% interanual, y acumulan una ca\u00edda del 2,1% en el arranque del 2026. En el intermensual, crecieron 8,8%.<\/p>\n<p>-Farmacia: las ventas subieron un 0,3% interanual y acumulan un alza del 2,4% en lo que va del a\u00f1o. En tanto, en la comparaci\u00f3n intermensual, siempre desestacionalizada, se registr\u00f3 una merma del 0,2%.<\/p>\n<p>-Perfumer\u00eda: las ventas cayeron un 10,7% interanual, pero suman un incremento del 2,8% en el primer bimestre. En la comparaci\u00f3n intermensual, hubo una baja del 4,7%.<\/p>\n<p>-Ferreter\u00eda, materiales el\u00e9ctricos y materiales de la construcci\u00f3n: las ventas tuvieron una baja del 0,3% pero acumulan un crecimiento del 2,5% en el inicio de 2026. Por su parte, en el intermensual retrocedieron 3,1%<\/p>\n<p>-Textil e indumentaria: las ventas cayeron un 7,4% interanual, a precios constantes, y acumulan un descenso del 9,2%. En la comparaci\u00f3n intermensual desestacionalizada, se observ\u00f3 una ca\u00edda del 5,1%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo se\u00f1al\u00f3 el relevamiento publicado por CAME. El desplome fue del 5,6% interanual, por lo que las ventas minoristas pymes llevan diez meses consecutivos en retroceso. El desempe\u00f1o de cada sector. Las ventas minoristas de las pymes retrocedieron el 5,6% interanual en febrero y cayeron por d\u00e9cimo mes consecutivo. As\u00ed, acumularon un desplome del 5,2% [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-4701","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=4701"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4701\/revisions"}],"predecessor-version":[{"id":4703,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/4701\/revisions\/4703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/4702"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=4701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=4701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=4701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}