{"id":2983,"date":"2025-12-10T15:39:49","date_gmt":"2025-12-10T18:39:49","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=2983"},"modified":"2025-12-10T15:39:49","modified_gmt":"2025-12-10T18:39:49","slug":"alarma-en-reino-unido-cierran-escuelas-por-brote-de-gripe-h3n2","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/12\/10\/alarma-en-reino-unido-cierran-escuelas-por-brote-de-gripe-h3n2\/","title":{"rendered":"Alarma en Reino Unido: cierran escuelas por brote de gripe H3N2"},"content":{"rendered":"<p>La cepa es altamente transmisible y los expertos recomiendan la vacunaci\u00f3n inmediata.<\/p>\n<p>Varios colegios del Reino Unido debieron cerrar temporalmente sus puertas en los \u00faltimos d\u00edas, debido a un repunte inusual de la gripe estacional, causada por una mutaci\u00f3n de la subvariante H3N2 conocida como &#8220;subclade K&#8221;.<\/p>\n<p>El brote m\u00e1s significativo se produjo en Caerphilly (Gales), donde m\u00e1s de 250 alumnos y empleados se enfermaron de manera simult\u00e1nea. En consecuencia, las autoridades educativas optaron por una desinfecci\u00f3n profunda y la interrupci\u00f3n puntual de las clases para aminorar los contagios.<\/p>\n<p>Los s\u00edntomas entre los alumnos afectados (v\u00f3mitos, fiebre, diarrea, dolor de cabeza y fatiga), similares a los del Covid-19, obligaron a varios centros a suspender sus actividades. Adem\u00e1s, los escalofr\u00edos suelen aparecer muy bruscamente con esta cepa.<\/p>\n<p>La decisi\u00f3n se produce en un momento de presi\u00f3n creciente en el Sistema Nacional de Salud P\u00fablica (NHS), que ya registr\u00f3 1.717 hospitalizaciones por gripe a finales de noviembre, la cifra m\u00e1s alta de los \u00faltimos a\u00f1os para este periodo.<\/p>\n<p>En tanto, la Agencia de Seguridad Sanitaria brit\u00e1nica (UKHSA) advirti\u00f3 de que la mutaci\u00f3n increment\u00f3 la capacidad de transmisi\u00f3n del virus, aunque la eficacia de la vacuna se mantiene estable respecto a temporadas anteriores.<\/p>\n<p>Como esta nueva variante de gripe H3N2 sublcado K, es altamente transmisible, los expertos prev\u00e9n un fuerte aumento de casos y advirtieron el riesgo de infecciones dobles (gripe y gripe aviar) y aconsejaron una vacunaci\u00f3n de manera urgente.<\/p>\n<p>La alta transmisibilidad de esta variante se atribuye a cambios gen\u00e9ticos significativos dentro del subclado K. S, seg\u00fan los expertos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cepa es altamente transmisible y los expertos recomiendan la vacunaci\u00f3n inmediata. Varios colegios del Reino Unido debieron cerrar temporalmente sus puertas en los \u00faltimos d\u00edas, debido a un repunte inusual de la gripe estacional, causada por una mutaci\u00f3n de la subvariante H3N2 conocida como &#8220;subclade K&#8221;. El brote m\u00e1s significativo se produjo en Caerphilly [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-2983","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=2983"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2983\/revisions"}],"predecessor-version":[{"id":2986,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2983\/revisions\/2986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/2985"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=2983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=2983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=2983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}