{"id":2976,"date":"2025-12-10T15:34:41","date_gmt":"2025-12-10T18:34:41","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=2976"},"modified":"2025-12-10T15:34:41","modified_gmt":"2025-12-10T18:34:41","slug":"javier-milei-celebro-sus-primeros-dos-anos-en-la-presidencia","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/12\/10\/javier-milei-celebro-sus-primeros-dos-anos-en-la-presidencia\/","title":{"rendered":"Javier Milei celebr\u00f3 sus primeros dos a\u00f1os en la Presidencia"},"content":{"rendered":"<p>El presidente Javier Milei cumpli\u00f3 este mi\u00e9rcoles dos a\u00f1os de gesti\u00f3n y lo celebr\u00f3 en su cuenta de X: &#8220;Muchas gracias&#8221;. __IP__<\/p>\n<p>Milei poste\u00f3 una imagen junto a su hermana, la secretaria General de la Presidencia, Karina Milei, el d\u00eda de la asunci\u00f3n, el 10 de diciembre de 2023.<\/p>\n<p>El libertario se encuentra en Oslo donde estaba previsto que participara de la ceremonia de entrega del Premio Nobel de la Paz para la dirigente venezolana Mar\u00eda Corina Machado.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Javier Milei cumpli\u00f3 este mi\u00e9rcoles dos a\u00f1os de gesti\u00f3n y lo celebr\u00f3 en su cuenta de X: &#8220;Muchas gracias&#8221;. __IP__ Milei poste\u00f3 una imagen junto a su hermana, la secretaria General de la Presidencia, Karina Milei, el d\u00eda de la asunci\u00f3n, el 10 de diciembre de 2023. El libertario se encuentra en Oslo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-2976","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=2976"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2976\/revisions"}],"predecessor-version":[{"id":2978,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2976\/revisions\/2978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/2977"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=2976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=2976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=2976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}