{"id":2329,"date":"2025-11-11T10:55:34","date_gmt":"2025-11-11T13:55:34","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=2329"},"modified":"2025-11-11T10:55:34","modified_gmt":"2025-11-11T13:55:34","slug":"el-grupo-scout-goya-celebro-su-aniversario-n-58","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/11\/11\/el-grupo-scout-goya-celebro-su-aniversario-n-58\/","title":{"rendered":"El Grupo Scout Goya celebr\u00f3 su aniversario N\u00b0 58"},"content":{"rendered":"<p>El Grupo Scout Nuestra Se\u00f1ora del Rosario 613 \u2013 282, el pasado s\u00e1bado 8 de noviembre en su sede celebr\u00f3 una emotiva velada scout con motivo de festejar los 58 a\u00f1os de estar \u201cSiempre Listo\u201d; con la participaci\u00f3n de m\u00e1s de 200 personas, reuniendo a distintas generaciones que formaron y siguen formando parte de esta gran familia.<\/p>\n<p>La noche cont\u00f3 con la presencia del maestro scout Oreste Jorge Colonese, quien acompa\u00f1\u00f3 este importante momento de encuentro y recuerdos compartidos.<\/p>\n<p>Durante la velada hubo la formulaci\u00f3n de una promesa scouts de la protagonista F\u00e1tima Nicoletti.<\/p>\n<p>M\u00fasicos, bailarines, proyecci\u00f3n de un video y menciones especiales, dieron un marco de emoci\u00f3n y alegr\u00eda a una jornada llena de esp\u00edritu scout.<\/p>\n<p>Dentro de las menciones especiales, uno de los destinatarios de ese reconocimiento ha sido el director de Cultura Manuel Zampar, quien expres\u00f3: \u201cEstoy muy agradecido por esta distinci\u00f3n, junto a Jorge (Colonese) hemos recordado an\u00e9cdotas que han quedado grabadas de manera firmes en mi coraz\u00f3n, mi familia, mi esposa siempre me recuerda por actitudes, gestos, \u201cse nota que sos scout\u201d. Solo me resta agradecerte Jorge por esas ense\u00f1anzas que quedan para toda la vida\u201d.<\/p>\n<p>El Grupo Scout de Goya a modo de gratitud por las gestiones y facilidades brindadas desde la Direcci\u00f3n de Cultura, obsequi\u00f3 a Manuel Zampar el libro de la memoria del grupo para que sea destinado a la Biblioteca de la Casa de la Cultura.<\/p>\n<p>La celebraci\u00f3n continu\u00f3 con una rica cena compartida y culmin\u00f3 con la tradicional torta y el canto del feliz cumplea\u00f1os, honrando los 58 a\u00f1os de historia, servicio y amistad del grupo.<\/p>\n<p>Los dirigentes agradecieron a la familia scout, por confiar, acompa\u00f1ar y seguir caminando juntos en este hermoso camino de formaci\u00f3n de j\u00f3venes y adultos.<\/p>\n<p>Motivados con el lema identificatorio: \u00a1Siempre Listo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Scout Nuestra Se\u00f1ora del Rosario 613 \u2013 282, el pasado s\u00e1bado 8 de noviembre en su sede celebr\u00f3 una emotiva velada scout con motivo de festejar los 58 a\u00f1os de estar \u201cSiempre Listo\u201d; con la participaci\u00f3n de m\u00e1s de 200 personas, reuniendo a distintas generaciones que formaron y siguen formando parte de esta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2330,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-2329","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=2329"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2329\/revisions"}],"predecessor-version":[{"id":2331,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2329\/revisions\/2331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/2330"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=2329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=2329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=2329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}