{"id":2129,"date":"2025-11-04T15:47:55","date_gmt":"2025-11-04T18:47:55","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=2129"},"modified":"2025-11-04T15:47:55","modified_gmt":"2025-11-04T18:47:55","slug":"anunciaron-un-aumento-salarial-del-60-para-los-trabajadores-del-hospital-garrahan","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/11\/04\/anunciaron-un-aumento-salarial-del-60-para-los-trabajadores-del-hospital-garrahan\/","title":{"rendered":"Anunciaron un aumento salarial del 60% para los trabajadores del Hospital Garrahan"},"content":{"rendered":"<p>Se trata de un incremento para el personal de planta, contratos de empleo p\u00fablico, becarios y residentes con Beca Instituci\u00f3n.<\/p>\n<p>El Gobierno confirm\u00f3 un &#8220;aumento hist\u00f3rico&#8221; cercano al 60% en la asignaci\u00f3n b\u00e1sica para los trabajadores del Hospital Garrahan.<\/p>\n<p>Seg\u00fan informaron a trav\u00e9s de un comunicado, se trata de un incremento para el personal de planta, contratos de empleo p\u00fablico, becarios y residentes con Beca Instituci\u00f3n.<\/p>\n<p>&#8220;Desde el 10 de diciembre de 2023, con el inicio de la nueva gesti\u00f3n nacional, el Garrahan comenz\u00f3 un proceso profundo de orden, transparencia y eficiencia&#8221;, comienza el texto que se public\u00f3 en las redes oficiales del centro de salud pedi\u00e1trico.<\/p>\n<p>Tras ello, se remarc\u00f3 el aceleramiento del &#8220;bono mensual fijo de $350.000 para el personal no asistencial y de $450.000 para el personal asistencial&#8221;. Esto, destacaron desde el Gobierno, &#8220;se logr\u00f3 con recursos propios y sin afectar la sostenibilidad del hospital&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un incremento para el personal de planta, contratos de empleo p\u00fablico, becarios y residentes con Beca Instituci\u00f3n. El Gobierno confirm\u00f3 un &#8220;aumento hist\u00f3rico&#8221; cercano al 60% en la asignaci\u00f3n b\u00e1sica para los trabajadores del Hospital Garrahan. Seg\u00fan informaron a trav\u00e9s de un comunicado, se trata de un incremento para el personal de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-2129","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=2129"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2129\/revisions"}],"predecessor-version":[{"id":2132,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2129\/revisions\/2132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/2131"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=2129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=2129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=2129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}