{"id":2056,"date":"2025-11-02T15:11:28","date_gmt":"2025-11-02T18:11:28","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=2056"},"modified":"2025-11-02T15:11:28","modified_gmt":"2025-11-02T18:11:28","slug":"benjamin-matienzo-se-quedo-con-la-copa-ciudad-de-goya","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/11\/02\/benjamin-matienzo-se-quedo-con-la-copa-ciudad-de-goya\/","title":{"rendered":"Benjam\u00edn Matienzo se qued\u00f3 con la Copa &#8220;Ciudad de Goya&#8221;"},"content":{"rendered":"<p>Este fin de semana, Benjam\u00edn Matienzo se qued\u00f3 con el t\u00edtulo del Torneo Octogonal 2025 de la Liga Goyana de F\u00fatbol tras vencer a Central Goya por 3 a 1. Justo Sosa, Mauro Moreira y Juan Pablo Fern\u00e1ndez marcaron para el flamante campe\u00f3n. Por su parte, Lautaro Valenzuela hab\u00eda anotado en la primera mitad para Central.<\/p>\n<p>En esta temporada, el Pitog\u00fc\u00e9 sali\u00f3 campe\u00f3n invicto del Torneo Clausura y subcampe\u00f3n invicto del Oficial. Ahora pudo sumar la Copa Ciudad de Goya a sus vitrinas para seguir escribiendo historia en una de las ligas hist\u00f3ricas del interior.<\/p>\n<p>Torneo Regional Federal Amateur: duelos en Goya y Monte Caseros<\/p>\n<p>Hoy seguir\u00e1 la acci\u00f3n el segunda fecha del Torneo Regional Federal Amateur (TRFA) con duelos en el interior.<\/p>\n<p>En Goya, por la Zona 3 de la Regi\u00f3n Litoral Norte, Sportivo Surub\u00ed de Goya har\u00e1 su debut enfrentando a Atl\u00e9tico Defensores de San Roque (desde las 16). Mientras que, por la Zona 5, San Lorenzo de Monte Caseros recibir\u00e1 a Madariaga de Paso de los Libres (desde las 17:30). Francisco Pedro Vargas (\u00e1rbitro de la Liga Goyana) ser\u00e1 el juez principal de este encuentro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana, Benjam\u00edn Matienzo se qued\u00f3 con el t\u00edtulo del Torneo Octogonal 2025 de la Liga Goyana de F\u00fatbol tras vencer a Central Goya por 3 a 1. Justo Sosa, Mauro Moreira y Juan Pablo Fern\u00e1ndez marcaron para el flamante campe\u00f3n. Por su parte, Lautaro Valenzuela hab\u00eda anotado en la primera mitad para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-2056","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=2056"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2056\/revisions"}],"predecessor-version":[{"id":2059,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/2056\/revisions\/2059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/2058"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=2056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=2056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=2056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}