{"id":1641,"date":"2025-10-14T04:03:20","date_gmt":"2025-10-14T07:03:20","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=1641"},"modified":"2025-10-14T04:04:56","modified_gmt":"2025-10-14T07:04:56","slug":"en-conferencia-de-prensa-lionel-scaloni-confirmo-que-messi-tendra-minutos-ante-puerto-rico","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/10\/14\/en-conferencia-de-prensa-lionel-scaloni-confirmo-que-messi-tendra-minutos-ante-puerto-rico\/","title":{"rendered":"En Conferencia de Prensa Lionel Scaloni confirm\u00f3 que Messi tendr\u00e1 minutos ante Puerto Rico"},"content":{"rendered":"<p>El entrenador de la Selecci\u00f3n Argentina ofreci\u00f3 una conferencia de prensa previa al amistoso contra seleccionado centroamericano, abordando temas como la participaci\u00f3n de Messi, las nuevas convocatorias, la situaci\u00f3n de los arqueros, y el respeto por los rivales de CONCACAF.<\/p>\n<p>Lionel Scaloni ofreci\u00f3 una conferencia de prensa antes del partido amistoso contra Puerto Rico, donde abord\u00f3 varios temas importantes relacionados con la selecci\u00f3n argentina.<\/p>\n<p>Uno de los puntos centrales fue la situaci\u00f3n de Lionel Messi. Scaloni confirm\u00f3 que Messi termin\u00f3 bien el partido del fin de semana y que hablar\u00e1 con \u00e9l antes del entrenamiento final para determinar si ser\u00e1 titular. Anticip\u00f3 que, si Messi est\u00e1 en condiciones, jugar\u00e1 algunos minutos para que la afici\u00f3n pueda disfrutarlo.<\/p>\n<p>Scaloni tambi\u00e9n se refiri\u00f3 a las nuevas caras en la convocatoria, como An\u00edbal Moreno y el Flaco L\u00f3pez. Confirm\u00f3 que algunos de estos jugadores tendr\u00e1n la oportunidad de jugar contra Puerto Rico para demostrar su val\u00eda y ver si pueden seguir siendo considerados para futuras convocatorias. La idea es mantener una base similar para las pr\u00f3ximas fechas, pero siempre estando abiertos a nuevos talentos.<\/p>\n<p>En cuanto al arco, Scaloni mencion\u00f3 que Emiliano Mart\u00ednez (Dibu) quiere jugar siempre, y seguramente ser\u00e1 titular contra Puerto Rico. Sin embargo, adelant\u00f3 que en noviembre planean probar otras opciones en la porter\u00eda.<\/p>\n<p>Scaloni tambi\u00e9n respondi\u00f3 preguntas sobre Mat\u00edas Soul\u00e9, destacando que est\u00e1 en el radar de la selecci\u00f3n, al igual que otros j\u00f3venes como Buonanotte, Garnacho y Carboni. La idea es convocarlos cuando se vea la oportunidad.<\/p>\n<p>Respecto a la pregunta sobre qu\u00e9 busca en un jugador para la selecci\u00f3n, Scaloni enfatiz\u00f3 que lo principal es que juegue bien y que entienda el estilo de f\u00fatbol que propone el equipo. Tambi\u00e9n valor\u00f3 la actitud y las ganas de competir del grupo en general, destacando que el alma del equipo es que todos ganan y pierden juntos.<\/p>\n<p>En relaci\u00f3n a los partidos amistosos contra rivales de la CONCACAF, Scaloni expres\u00f3 respeto por el f\u00fatbol de esta regi\u00f3n y enfatiz\u00f3 que no hay rival f\u00e1cil. En particular, mencion\u00f3 a M\u00e9xico, destacando su cultura futbol\u00edstica y su gran selecci\u00f3n. No considera que haya una rivalidad especial m\u00e1s all\u00e1 de la que se vive en cada partido entre selecciones hist\u00f3ricas.<\/p>\n<p>Scaloni tambi\u00e9n habl\u00f3 sobre los j\u00f3venes Mastantuono y el Flaco L\u00f3pez. Dijo que L\u00f3pez ha tenido un crecimiento importante en los \u00faltimos meses y est\u00e1 demostrando su val\u00eda. Respecto a Mastantuono, mencion\u00f3 que est\u00e1 madurando poco a poco y que tendr\u00e1 la importancia que el cuerpo t\u00e9cnico considere adecuada.<\/p>\n<p>Finalmente, Scaloni destac\u00f3 el trabajo que se est\u00e1 haciendo en las divisiones juveniles argentinas, resaltando el amor por la camiseta y el esfuerzo que transmiten a los j\u00f3venes jugadores. Envi\u00f3 un mensaje a los j\u00f3venes futbolistas de Puerto Rico, anim\u00e1ndolos a so\u00f1ar y a intentar alcanzar sus metas, recordando que el camino es lo m\u00e1s importante.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El entrenador de la Selecci\u00f3n Argentina ofreci\u00f3 una conferencia de prensa previa al amistoso contra seleccionado centroamericano, abordando temas como la participaci\u00f3n de Messi, las nuevas convocatorias, la situaci\u00f3n de los arqueros, y el respeto por los rivales de CONCACAF. Lionel Scaloni ofreci\u00f3 una conferencia de prensa antes del partido amistoso contra Puerto Rico, donde [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-1641","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1641\/revisions"}],"predecessor-version":[{"id":1643,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1641\/revisions\/1643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/1644"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=1641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}