{"id":1614,"date":"2025-10-14T02:59:10","date_gmt":"2025-10-14T05:59:10","guid":{"rendered":"https:\/\/radiokissnoticias.com.ar\/web\/?p=1614"},"modified":"2025-10-14T02:59:10","modified_gmt":"2025-10-14T05:59:10","slug":"direccion-de-transito-de-goya-colabora-y-asiste-en-varios-frentes-para-sostener-la-seguridad-vial-ciudadana","status":"publish","type":"post","link":"https:\/\/radiokissnoticias.com.ar\/web\/2025\/10\/14\/direccion-de-transito-de-goya-colabora-y-asiste-en-varios-frentes-para-sostener-la-seguridad-vial-ciudadana\/","title":{"rendered":"Direcci\u00f3n de Tr\u00e1nsito de Goya, colabora y asiste en varios frentes para sostener la seguridad vial ciudadana"},"content":{"rendered":"<p class=\"rtejustify\">La Direcci\u00f3n de Tr\u00e1nsito abarca varios frentes lo que permite abordar la prevenci\u00f3n desde distintas estrategias como la educaci\u00f3n, el control y la concientizaci\u00f3n. El objetivo es promover la educaci\u00f3n vial y la toma de conciencia sobre la importancia de la seguridad en el tr\u00e1nsito.<\/p>\n<p class=\"rtejustify\">Uno de estos frentes se dio durante la jornada del domingo en la sede del establecimiento educativo de la alternancia, ubicado en el Paraje Maruchas: EFA COEMBOTA.<\/p>\n<p class=\"rtejustify\">Este fue el punto de encuentro para la muestra de los ciclos productivos que desarrollan los estudiantes.<\/p>\n<p class=\"rtejustify\">All\u00ed se destac\u00f3 el espacio para la seguridad vial brindado por el Director de Tr\u00e1nsito de la Municipalidad de Goya Lic. Alejandro Stortti y el aporte testimonial de integrantes de la Fundaci\u00f3n Estrellas Amarillas.<\/p>\n<p class=\"rtejustify\">\u201cAcudimos con un espacio, un simulador de manejo, las madres de estrellas amarillas colaboraron, fue interesante las actividades con los chicos, tomando pruebas de manejo, evadiendo conos, una charla de seguridad vial, desde la ma\u00f1ana hasta la tarde estuvimos ah\u00ed, les gust\u00f3 mucho\u201d, relat\u00f3 Stortti.<\/p>\n<p class=\"rtejustify\">Cabe se\u00f1alar que esta dependencia, la ma\u00f1ana del lunes 13 estuvo presente en Guarder\u00eda \u201cMama Perla\u201d con educaci\u00f3n vial y en la semana asistir\u00e1 a escuelas primarias y secundarias con parque tem\u00e1tico.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"rtejustify\"><strong>SEM\u00c1FOROS INTERMITENTES<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"rtejustify\">Se habilitaron algunos sem\u00e1foros para que permanezcan en intermitente en algunos cruces y giros peligrosos. Estos estar\u00e1n adecuadamente se\u00f1alizados. Se solicita a la ciudadan\u00eda conducir con precauci\u00f3n, atendiendo a la nueva se\u00f1alizaci\u00f3n y por, sobre todo, respetando la velocidad indicada.<\/p>\n<p class=\"rtejustify\">\u201cLos activamos ahora, son 3 sem\u00e1foros que arreglamos, uno est\u00e1 ubicado en Alem y Paso de los Libres, el otro en Francisco S\u00e1 y D\u00edaz Colodrero y otro en Per\u00f3n y Alemania (el tri\u00e1ngulo)\u201d, enumer\u00f3 el funcionario de Tr\u00e1nsito.<\/p>\n<p class=\"rtejustify\">Hoy por hoy la ciudad de Goya cuenta con 42 sem\u00e1foros ubicados en distintas intersecciones los cuales son reparados o movidos de lugar seg\u00fan la utilizaci\u00f3n que se requiera. Hay un plan presentado al intendente Hormaechea (Goya 2030) donde se le exhibe la necesidad de implementar la puesta de 50 sem\u00e1foros m\u00e1s, tanto en microcentro como en accesos principales a la ciudad y los barrios.<\/p>\n<p class=\"rtejustify\">\u201cHoy d\u00eda estamos solicitando una inversi\u00f3n de 20 millones para semaforizar dos esquinas claves con mucho flujo como son: Sarmiento y Belgrano y la otra es D\u00edaz Colodrero y Rol\u00f3n\u201d dijo.<\/p>\n<p class=\"rtejustify\">\n<p class=\"rtejustify\"><strong>OPERATIVOS CON POLIC\u00cdA DE LA PROVINCIA<\/strong><\/p>\n<p class=\"rtejustify\">\n<p class=\"rtejustify\">Contin\u00faa el trabajo de manera conjunta en materia de seguridad vial, como ser los operativos de alcoholemia y mayor control vehicular. Esta tarea se realiza con la Polic\u00eda de la Provincia de Corrientes.<\/p>\n<p class=\"rtejustify\">Estos dispositivos se implementan en forma diaria sobre todo a conductores de motos en la detecci\u00f3n de ca\u00f1os de escapes libres y documentaci\u00f3n \u201clo que ha hecho que se reduzcan bastante los siniestros viales\u201d, indic\u00f3.<\/p>\n<p class=\"rtejustify\">\u201cEsto operativos se hacen en forma constante todos los fines de semana en distintos puntos de la ciudad. Se hacen operativos en un lugar, levantamos y nos vamos a otro lugar como zonas de El Ing\u00e1, Rol\u00f3n y Sarmiento. Los fines de semana suelen ser con mucho trabajo, este fin de semana se retuvieron m\u00e1s de 18 motos por falta de documentaci\u00f3n, escape libre, alcoholemia\u201d.<\/p>\n<p class=\"rtejustify\">Durante los procedimientos se identifican personas y veh\u00edculos, haciendo uso del sistema 911 para verificar si existe alg\u00fan impedimento de circulaci\u00f3n. Stortti subray\u00f3 que muchas de las irregularidades detectadas corresponden al uso de motocicletas con ca\u00f1os de escape libre, sin carenados, sin espejos y luces entre otras.<\/p>\n<p class=\"rtejustify\">Asimismo, insisti\u00f3 en la necesidad de ser rigurosos con los conductores de estas motos, especialmente frente a maniobras peligrosas como las \u201cpicadas\u201d o \u201cWilly\u201d, que ponen en riesgo tanto al conductor como a terceros.<\/p>\n<p class=\"rtejustify\">\u201cEs una cuesti\u00f3n para preservar la integridad f\u00edsica de los ciudadanos, cuesta entender esto, sigue llevando vidas andar sin casco, lamentablemente es una sociedad que no logra entender y tiene que salir el inspector a explicar cientos de veces con campa\u00f1as, pero en alg\u00fan momento nos tendr\u00e1 que hacer clic la cabeza a todos a ver si empezamos a usar el casco\u201d, enfatiz\u00f3 Stortti.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"rtejustify\"><strong>CORTES DE CALLE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"rtejustify\">Para garantizar la seguridad vial de los espectadores y ciudadanos, personal de esa dependencia implementa operativo especiales de tr\u00e1nsito con distintos motivos y es parte del servicio que brinda Tr\u00e1nsito a la comunidad, en casos de actividades que involucra movilidad social como manifestaciones, festejos populares, bicicleteadas, caravanas, trabajos de pintura en pavimento, eventos varios.<\/p>\n<p class=\"rtejustify\">En este sentido, este fin de semana se implement\u00f3 operativo durante la caravana de los hinchas del Club Sportivo Benjam\u00edn Matienzo, por el logro del Campeonato de Primera Divisi\u00f3n del f\u00fatbol masculino.<\/p>\n<p class=\"rtejustify\">Recordemos que el \u201cPitog\u00fce\u201d lleg\u00f3 a sus 43 t\u00edtulos Oficiales en la Liga Goyana de F\u00fatbol.<\/p>\n<p class=\"rtejustify\">Asimismo, tuvo presencia en un evento religioso en la salida de Goya y en una marat\u00f3n en zona norte. Se colabora en zona de obra de ampliaci\u00f3n de ruta Provincial N\u00b0 27, desde la Rotonda Virgen de Rosario hasta Puente Santa Luc\u00eda.<\/p>\n<p class=\"rtejustify\">Las acciones, que se ejecutan diariamente en distintos puntos de la ciudad, buscan garantizar el orden vehicular, prevenir infracciones y fortalecer la presencia institucional en la v\u00eda p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n de Tr\u00e1nsito abarca varios frentes lo que permite abordar la prevenci\u00f3n desde distintas estrategias como la educaci\u00f3n, el control y la concientizaci\u00f3n. El objetivo es promover la educaci\u00f3n vial y la toma de conciencia sobre la importancia de la seguridad en el tr\u00e1nsito. Uno de estos frentes se dio durante la jornada del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-1614","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local"],"_links":{"self":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=1614"}],"version-history":[{"count":1,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1614\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/1614\/revisions\/1616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/1615"}],"wp:attachment":[{"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=1614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=1614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiokissnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=1614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}